{"id":1018,"date":"2025-05-28T17:56:44","date_gmt":"2025-05-28T20:56:44","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/05\/28\/camara-analisa-novas-regras-de-processo-administrativo-tributario-e-solucao-consensual-de-conflitos\/"},"modified":"2025-05-28T17:56:44","modified_gmt":"2025-05-28T20:56:44","slug":"camara-analisa-novas-regras-de-processo-administrativo-tributario-e-solucao-consensual-de-conflitos","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/05\/28\/camara-analisa-novas-regras-de-processo-administrativo-tributario-e-solucao-consensual-de-conflitos\/","title":{"rendered":"C\u00e2mara analisa novas regras de processo administrativo tribut\u00e1rio e solu\u00e7\u00e3o consensual de conflitos"},"content":{"rendered":"<div>\n<p>O Projeto de Lei Complementar (PLP) 124\/22 muda as regras de atua\u00e7\u00e3o do fisco (Receita Federal e secretarias da fazenda de estados e munic\u00edpios) para prevenir e solucionar conflitos tribut\u00e1rios e aduaneiros. Entre as novidades est\u00e3o a limita\u00e7\u00e3o das multas a 75% do imposto devido e a proibi\u00e7\u00e3o de multas de mora em casos de [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/05\/28\/camara-analisa-novas-regras-de-processo-administrativo-tributario-e-solucao-consensual-de-conflitos\/\">C\u00e2mara analisa novas regras de processo administrativo tribut\u00e1rio e solu\u00e7\u00e3o consensual de conflitos<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Projeto de Lei Complementar (PLP) 124\/22 muda as regras de atua\u00e7\u00e3o do fisco (Receita Federal e secretarias da fazenda de estados e munic\u00edpios) para prevenir e solucionar conflitos tribut\u00e1rios e aduaneiros. Entre as novidades est\u00e3o a limita\u00e7\u00e3o das multas a 75% do imposto devido e a proibi\u00e7\u00e3o de multas de mora em casos de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1018","post","type-post","status-publish","format-standard","hentry","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1018"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1018\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}