{"id":1033,"date":"2025-06-03T21:28:22","date_gmt":"2025-06-04T00:28:22","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/06\/03\/rs-programa-de-autorregularizacao-busca-recuperar-r-22-milhoes-em-icms-devidos-no-setor-de-bebidas-vegetais\/"},"modified":"2025-06-03T21:28:22","modified_gmt":"2025-06-04T00:28:22","slug":"rs-programa-de-autorregularizacao-busca-recuperar-r-22-milhoes-em-icms-devidos-no-setor-de-bebidas-vegetais","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/06\/03\/rs-programa-de-autorregularizacao-busca-recuperar-r-22-milhoes-em-icms-devidos-no-setor-de-bebidas-vegetais\/","title":{"rendered":"RS: Programa de autorregulariza\u00e7\u00e3o busca recuperar R$ 2,2 milh\u00f5es em ICMS devidos no setor de bebidas vegetais"},"content":{"rendered":"<div>\n<p>A Receita Estadual lan\u00e7ou um novo programa de autorregulariza\u00e7\u00e3o voltado a contribuintes do setor de bebidas vegetais. Os casos envolvem opera\u00e7\u00f5es internas de comercializa\u00e7\u00e3o destinadas ao consumidor final, nas quais os contribuintes aplicaram al\u00edquota inferior \u00e0 prevista na legisla\u00e7\u00e3o, que \u00e9 de 25%. A pr\u00e1tica resultou em erros no c\u00e1lculo do imposto e na consequente [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/06\/03\/rs-programa-de-autorregularizacao-busca-recuperar-r-22-milhoes-em-icms-devidos-no-setor-de-bebidas-vegetais\/\">RS: Programa de autorregulariza\u00e7\u00e3o busca recuperar R$ 2,2 milh\u00f5es em ICMS devidos no setor de bebidas vegetais<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Receita Estadual lan\u00e7ou um novo programa de autorregulariza\u00e7\u00e3o voltado a contribuintes do setor de bebidas vegetais. Os casos envolvem opera\u00e7\u00f5es internas de comercializa\u00e7\u00e3o destinadas ao consumidor final, nas quais os contribuintes aplicaram al\u00edquota inferior \u00e0 prevista na legisla\u00e7\u00e3o, que \u00e9 de 25%. A pr\u00e1tica resultou em erros no c\u00e1lculo do imposto e na consequente [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,29],"tags":[],"class_list":["post-1033","post","type-post","status-publish","format-standard","hentry","category-icms","category-sefaz","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1033"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1033\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}