{"id":1075,"date":"2025-06-16T20:55:05","date_gmt":"2025-06-16T23:55:05","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/06\/16\/juiz-reconhece-direito-de-incluir-ipi-nao-recuperavel-na-base-de-calculo-de-pis-e-cofins\/"},"modified":"2025-06-16T20:55:05","modified_gmt":"2025-06-16T23:55:05","slug":"juiz-reconhece-direito-de-incluir-ipi-nao-recuperavel-na-base-de-calculo-de-pis-e-cofins","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/06\/16\/juiz-reconhece-direito-de-incluir-ipi-nao-recuperavel-na-base-de-calculo-de-pis-e-cofins\/","title":{"rendered":"Juiz reconhece direito de incluir IPI n\u00e3o recuper\u00e1vel na base de c\u00e1lculo de PIS e Cofins"},"content":{"rendered":"<div>\n<p>Ao excluir o IPI n\u00e3o recuper\u00e1vel da base de c\u00e1lculo dos cr\u00e9ditos de PIS e Cofins, a Instru\u00e7\u00e3o Normativa RFB 2.121\/2022 ultrapassou seu papel regulamentar, comprometendo a efetividade do princ\u00edpio da n\u00e3o cumulatividade. Esse foi o entendimento do juiz Pedro Lucas Leite L\u00f4bo Siebra, da 1\u00aa Vara Federal C\u00edvel e Criminal da SSJ de Feira [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/06\/16\/juiz-reconhece-direito-de-incluir-ipi-nao-recuperavel-na-base-de-calculo-de-pis-e-cofins\/\">Juiz reconhece direito de incluir IPI n\u00e3o recuper\u00e1vel na base de c\u00e1lculo de PIS e Cofins<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ao excluir o IPI n\u00e3o recuper\u00e1vel da base de c\u00e1lculo dos cr\u00e9ditos de PIS e Cofins, a Instru\u00e7\u00e3o Normativa RFB 2.121\/2022 ultrapassou seu papel regulamentar, comprometendo a efetividade do princ\u00edpio da n\u00e3o cumulatividade. Esse foi o entendimento do juiz Pedro Lucas Leite L\u00f4bo Siebra, da 1\u00aa Vara Federal C\u00edvel e Criminal da SSJ de Feira [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-1075","post","type-post","status-publish","format-standard","hentry","category-ipi","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1075"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1075\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}