{"id":1131,"date":"2025-07-07T20:09:51","date_gmt":"2025-07-07T23:09:51","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/07\/07\/rs-conselho-nacional-de-politica-fazendaria-aprova-proposta-de-destinacao-de-parte-do-icms-para-hospitais-publicos-gauchos\/"},"modified":"2025-07-07T20:09:51","modified_gmt":"2025-07-07T23:09:51","slug":"rs-conselho-nacional-de-politica-fazendaria-aprova-proposta-de-destinacao-de-parte-do-icms-para-hospitais-publicos-gauchos","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/07\/07\/rs-conselho-nacional-de-politica-fazendaria-aprova-proposta-de-destinacao-de-parte-do-icms-para-hospitais-publicos-gauchos\/","title":{"rendered":"RS: Conselho Nacional de Pol\u00edtica Fazend\u00e1ria aprova proposta de destina\u00e7\u00e3o de parte do ICMS para hospitais p\u00fablicos ga\u00fachos"},"content":{"rendered":"<div>\n<p>O Conselho Nacional de Pol\u00edtica Fazend\u00e1ria (Confaz) aprovou, nesta sexta-feira (4\/7), pedido encaminhado pelo governo do Estado para autoriza\u00e7\u00e3o de concess\u00e3o de cr\u00e9dito presumido de 100% dos valores destinados pelos contribuintes a hospitais filantr\u00f3picos, santas casas e hospitais p\u00fablicos estaduais e municipais que atendam o Sistema \u00danico de Sa\u00fade (SUS). A aprova\u00e7\u00e3o ocorreu em reuni\u00e3o [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/07\/07\/rs-conselho-nacional-de-politica-fazendaria-aprova-proposta-de-destinacao-de-parte-do-icms-para-hospitais-publicos-gauchos\/\">RS: Conselho Nacional de Pol\u00edtica Fazend\u00e1ria aprova proposta de destina\u00e7\u00e3o de parte do ICMS para hospitais p\u00fablicos ga\u00fachos<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Nacional de Pol\u00edtica Fazend\u00e1ria (Confaz) aprovou, nesta sexta-feira (4\/7), pedido encaminhado pelo governo do Estado para autoriza\u00e7\u00e3o de concess\u00e3o de cr\u00e9dito presumido de 100% dos valores destinados pelos contribuintes a hospitais filantr\u00f3picos, santas casas e hospitais p\u00fablicos estaduais e municipais que atendam o Sistema \u00danico de Sa\u00fade (SUS). A aprova\u00e7\u00e3o ocorreu em reuni\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1131","post","type-post","status-publish","format-standard","hentry","category-icms","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1131"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1131\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}