{"id":1140,"date":"2025-07-09T17:59:58","date_gmt":"2025-07-09T20:59:58","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/07\/09\/receita-federal-lanca-novas-funcionalidades-no-aplicativo-do-mei\/"},"modified":"2025-07-09T17:59:58","modified_gmt":"2025-07-09T20:59:58","slug":"receita-federal-lanca-novas-funcionalidades-no-aplicativo-do-mei","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/07\/09\/receita-federal-lanca-novas-funcionalidades-no-aplicativo-do-mei\/","title":{"rendered":"Receita Federal lan\u00e7a novas funcionalidades no aplicativo do MEI"},"content":{"rendered":"<div>\n<p>A Receita Federal anunciou, nesta quarta-feira (9\/7), o lan\u00e7amento da nova vers\u00e3o do aplicativo MEI, voltada a simplificar e tornar mais segura a gest\u00e3o do microempreendedor individual (MEI). A atualiza\u00e7\u00e3o do aplicativo, dispon\u00edvel gratuitamente para download nas lojas Google Play e App Store, apresenta tr\u00eas importantes novidades: D\u00e9bito autom\u00e1tico do Documento de Arrecada\u00e7\u00e3o do Simples [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/07\/09\/receita-federal-lanca-novas-funcionalidades-no-aplicativo-do-mei\/\">Receita Federal lan\u00e7a novas funcionalidades no aplicativo do MEI<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Receita Federal anunciou, nesta quarta-feira (9\/7), o lan\u00e7amento da nova vers\u00e3o do aplicativo MEI, voltada a simplificar e tornar mais segura a gest\u00e3o do microempreendedor individual (MEI). A atualiza\u00e7\u00e3o do aplicativo, dispon\u00edvel gratuitamente para download nas lojas Google Play e App Store, apresenta tr\u00eas importantes novidades: D\u00e9bito autom\u00e1tico do Documento de Arrecada\u00e7\u00e3o do Simples [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[131,10,36,11],"tags":[],"class_list":["post-1140","post","type-post","status-publish","format-standard","hentry","category-das","category-icms","category-iss","category-mei","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1140"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1140\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}