{"id":1145,"date":"2025-07-10T18:04:04","date_gmt":"2025-07-10T21:04:04","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/07\/10\/desequilibrio-tributario-faz-governo-perder-r-200-bi-anuais\/"},"modified":"2025-07-10T18:04:04","modified_gmt":"2025-07-10T21:04:04","slug":"desequilibrio-tributario-faz-governo-perder-r-200-bi-anuais","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/07\/10\/desequilibrio-tributario-faz-governo-perder-r-200-bi-anuais\/","title":{"rendered":"Desequil\u00edbrio tribut\u00e1rio faz governo perder R$ 200 bi anuais"},"content":{"rendered":"<div>\n<p>No momento em que o governo trava batalhas no Congresso Nacional e no Supremo Tribunal Federal (STF) sobre a cobran\u00e7a de impostos, aumento de arrecada\u00e7\u00e3o e justi\u00e7a tribut\u00e1ria, um estudo do Instituto de Pesquisa Econ\u00f4mica Aplicada (Ipea), \u00f3rg\u00e3o subordinado ao Minist\u00e9rio do Planejamento e Or\u00e7amento, aponta que discrep\u00e2ncias permitidas nas regras de cobran\u00e7a de impostos [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/07\/10\/desequilibrio-tributario-faz-governo-perder-r-200-bi-anuais\/\">Desequil\u00edbrio tribut\u00e1rio faz governo perder R$ 200 bi anuais<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>No momento em que o governo trava batalhas no Congresso Nacional e no Supremo Tribunal Federal (STF) sobre a cobran\u00e7a de impostos, aumento de arrecada\u00e7\u00e3o e justi\u00e7a tribut\u00e1ria, um estudo do Instituto de Pesquisa Econ\u00f4mica Aplicada (Ipea), \u00f3rg\u00e3o subordinado ao Minist\u00e9rio do Planejamento e Or\u00e7amento, aponta que discrep\u00e2ncias permitidas nas regras de cobran\u00e7a de impostos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[136,17,5],"tags":[],"class_list":["post-1145","post","type-post","status-publish","format-standard","hentry","category-justica-tributaria","category-reforma-tributaria","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1145"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1145\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}