{"id":1156,"date":"2025-07-14T21:12:57","date_gmt":"2025-07-15T00:12:57","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/07\/14\/rs-governo-do-estado-lanca-programa-para-negociacao-de-dividas-tributarias\/"},"modified":"2025-07-14T21:12:57","modified_gmt":"2025-07-15T00:12:57","slug":"rs-governo-do-estado-lanca-programa-para-negociacao-de-dividas-tributarias","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/07\/14\/rs-governo-do-estado-lanca-programa-para-negociacao-de-dividas-tributarias\/","title":{"rendered":"RS: Governo do Estado lan\u00e7a programa para negocia\u00e7\u00e3o de d\u00edvidas tribut\u00e1rias"},"content":{"rendered":"<div>\n<p>Programa Acordo Ga\u00facho prev\u00ea regulariza\u00e7\u00e3o de d\u00edvidas fiscais com condi\u00e7\u00f5es facilitadas de pagamento O governador Eduardo Leite assina nesta segunda-feira (14\/7), \u00e0s 17h, o decreto que regulamenta o Acordo Ga\u00facho, programa de transa\u00e7\u00e3o tribut\u00e1ria que vai permitir a regulariza\u00e7\u00e3o de d\u00edvidas fiscais com condi\u00e7\u00f5es facilitadas de pagamento. Com o decreto, o Estado poder\u00e1 lan\u00e7ar editais [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/07\/14\/rs-governo-do-estado-lanca-programa-para-negociacao-de-dividas-tributarias\/\">RS: Governo do Estado lan\u00e7a programa para negocia\u00e7\u00e3o de d\u00edvidas tribut\u00e1rias<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Programa Acordo Ga\u00facho prev\u00ea regulariza\u00e7\u00e3o de d\u00edvidas fiscais com condi\u00e7\u00f5es facilitadas de pagamento O governador Eduardo Leite assina nesta segunda-feira (14\/7), \u00e0s 17h, o decreto que regulamenta o Acordo Ga\u00facho, programa de transa\u00e7\u00e3o tribut\u00e1ria que vai permitir a regulariza\u00e7\u00e3o de d\u00edvidas fiscais com condi\u00e7\u00f5es facilitadas de pagamento. Com o decreto, o Estado poder\u00e1 lan\u00e7ar editais [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1156","post","type-post","status-publish","format-standard","hentry","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1156"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1156\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}