{"id":1184,"date":"2025-07-22T17:34:55","date_gmt":"2025-07-22T20:34:55","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/07\/22\/ecf-publicacao-da-versao-11-3-1-do-programa\/"},"modified":"2025-07-22T17:34:55","modified_gmt":"2025-07-22T20:34:55","slug":"ecf-publicacao-da-versao-11-3-1-do-programa","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/07\/22\/ecf-publicacao-da-versao-11-3-1-do-programa\/","title":{"rendered":"ECF: Publica\u00e7\u00e3o da Vers\u00e3o 11.3.1 do programa"},"content":{"rendered":"<div>\n<p>Vers\u00e3o 11.3.1 do Programa da ECF v\u00e1lida para o ano-calend\u00e1rio 2024 e situa\u00e7\u00f5es especiais de 2025, e para os anos anteriores. Foi publicada a vers\u00e3o 11.3.1 do programa da ECF, que deve ser utilizado para transmiss\u00f5es de arquivos da ECF referentes ao ano-calend\u00e1rio 2024 e situa\u00e7\u00f5es especiais de 2025 (leiaute 11), com as seguintes atualiza\u00e7\u00f5es: [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/07\/22\/ecf-publicacao-da-versao-11-3-1-do-programa\/\">ECF: Publica\u00e7\u00e3o da Vers\u00e3o 11.3.1 do programa<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vers\u00e3o 11.3.1 do Programa da ECF v\u00e1lida para o ano-calend\u00e1rio 2024 e situa\u00e7\u00f5es especiais de 2025, e para os anos anteriores. Foi publicada a vers\u00e3o 11.3.1 do programa da ECF, que deve ser utilizado para transmiss\u00f5es de arquivos da ECF referentes ao ano-calend\u00e1rio 2024 e situa\u00e7\u00f5es especiais de 2025 (leiaute 11), com as seguintes atualiza\u00e7\u00f5es: [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,14],"tags":[],"class_list":["post-1184","post","type-post","status-publish","format-standard","hentry","category-ecf","category-sped","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1184"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1184\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}