{"id":1189,"date":"2025-07-23T23:03:00","date_gmt":"2025-07-24T02:03:00","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/07\/23\/receita-federal-promove-live-sobre-novo-modulo-de-administracao-tributaria-no-portal-de-negocios-redesim\/"},"modified":"2025-07-23T23:03:00","modified_gmt":"2025-07-24T02:03:00","slug":"receita-federal-promove-live-sobre-novo-modulo-de-administracao-tributaria-no-portal-de-negocios-redesim","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/07\/23\/receita-federal-promove-live-sobre-novo-modulo-de-administracao-tributaria-no-portal-de-negocios-redesim\/","title":{"rendered":"Receita Federal promove live sobre novo m\u00f3dulo de Administra\u00e7\u00e3o Tribut\u00e1ria no Portal de Neg\u00f3cios Redesim"},"content":{"rendered":"<div>\n<p>A Receita Federal do Brasil convida a sociedade para participar de uma transmiss\u00e3o ao vivo que apresentar\u00e1 o novo M\u00f3dulo de Administra\u00e7\u00e3o Tribut\u00e1ria do Portal de Neg\u00f3cios Redesim (PNR), ferramenta que est\u00e1 transformando a forma como as pessoas jur\u00eddicas realizam seu registro e cumprem obriga\u00e7\u00f5es fiscais no pa\u00eds. A live ser\u00e1 realizada no dia 24 [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/07\/23\/receita-federal-promove-live-sobre-novo-modulo-de-administracao-tributaria-no-portal-de-negocios-redesim\/\">Receita Federal promove live sobre novo m\u00f3dulo de Administra\u00e7\u00e3o Tribut\u00e1ria no Portal de Neg\u00f3cios Redesim<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Receita Federal do Brasil convida a sociedade para participar de uma transmiss\u00e3o ao vivo que apresentar\u00e1 o novo M\u00f3dulo de Administra\u00e7\u00e3o Tribut\u00e1ria do Portal de Neg\u00f3cios Redesim (PNR), ferramenta que est\u00e1 transformando a forma como as pessoas jur\u00eddicas realizam seu registro e cumprem obriga\u00e7\u00f5es fiscais no pa\u00eds. A live ser\u00e1 realizada no dia 24 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[143,17,142,5],"tags":[],"class_list":["post-1189","post","type-post","status-publish","format-standard","hentry","category-pnr","category-reforma-tributaria","category-serpro","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1189"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1189\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}