{"id":1258,"date":"2025-08-10T18:07:33","date_gmt":"2025-08-10T21:07:33","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/08\/10\/ba-novo-sistema-de-gestao-de-itd-que-automatiza-calculo-do-tributo-ja-agilizou-mais-de-500-processos\/"},"modified":"2025-08-10T18:07:33","modified_gmt":"2025-08-10T21:07:33","slug":"ba-novo-sistema-de-gestao-de-itd-que-automatiza-calculo-do-tributo-ja-agilizou-mais-de-500-processos","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/08\/10\/ba-novo-sistema-de-gestao-de-itd-que-automatiza-calculo-do-tributo-ja-agilizou-mais-de-500-processos\/","title":{"rendered":"BA: Novo Sistema de Gest\u00e3o de ITD que automatiza c\u00e1lculo do tributo j\u00e1 agilizou mais de 500 processos"},"content":{"rendered":"<div>\n<p>Mais de 500 processos de ITD (Imposto sobre Transmiss\u00e3o \u201cCausa Mortis\u201d e Doa\u00e7\u00e3o de quaisquer Bens ou Direitos) j\u00e1 foram resolvidos de forma autom\u00e1tica por meio do novo sistema implantado pela Secretaria da Fazenda do Estado da Bahia (Sefaz-Ba) com o objetivo de agilizar o c\u00e1lculo nos casos de invent\u00e1rio, doa\u00e7\u00e3o e separa\u00e7\u00e3o. O Sistema [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/08\/10\/ba-novo-sistema-de-gestao-de-itd-que-automatiza-calculo-do-tributo-ja-agilizou-mais-de-500-processos\/\">BA: Novo Sistema de Gest\u00e3o de ITD que automatiza c\u00e1lculo do tributo j\u00e1 agilizou mais de 500 processos<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mais de 500 processos de ITD (Imposto sobre Transmiss\u00e3o \u201cCausa Mortis\u201d e Doa\u00e7\u00e3o de quaisquer Bens ou Direitos) j\u00e1 foram resolvidos de forma autom\u00e1tica por meio do novo sistema implantado pela Secretaria da Fazenda do Estado da Bahia (Sefaz-Ba) com o objetivo de agilizar o c\u00e1lculo nos casos de invent\u00e1rio, doa\u00e7\u00e3o e separa\u00e7\u00e3o. O Sistema [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[147,164,165,29,166],"tags":[],"class_list":["post-1258","post","type-post","status-publish","format-standard","hentry","category-ba","category-dae","category-itd","category-sefaz","category-tributo","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1258"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1258\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}