{"id":1303,"date":"2025-08-20T20:47:47","date_gmt":"2025-08-20T23:47:47","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/08\/20\/lucro-presumido-receita-define-percentuais-de-presuncao\/"},"modified":"2025-08-20T20:47:47","modified_gmt":"2025-08-20T23:47:47","slug":"lucro-presumido-receita-define-percentuais-de-presuncao","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/08\/20\/lucro-presumido-receita-define-percentuais-de-presuncao\/","title":{"rendered":"Lucro Presumido: Receita define percentuais de presun\u00e7\u00e3o"},"content":{"rendered":"<div>\n<p>A Receita Federal publicou recentemente solu\u00e7\u00f5es de consulta que esclarecem os percentuais de presun\u00e7\u00e3o aplic\u00e1veis ao Lucro Presumido em atividades espec\u00edficas, trazendo maior seguran\u00e7a jur\u00eddica para empresas e profissionais da \u00e1rea cont\u00e1bil. O Lucro Presumido \u00e9 um regime de tributa\u00e7\u00e3o simplificado que utiliza margens fixas de presun\u00e7\u00e3o para calcular a base do IRPJ e da [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/08\/20\/lucro-presumido-receita-define-percentuais-de-presuncao\/\">Lucro Presumido: Receita define percentuais de presun\u00e7\u00e3o<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Receita Federal publicou recentemente solu\u00e7\u00f5es de consulta que esclarecem os percentuais de presun\u00e7\u00e3o aplic\u00e1veis ao Lucro Presumido em atividades espec\u00edficas, trazendo maior seguran\u00e7a jur\u00eddica para empresas e profissionais da \u00e1rea cont\u00e1bil. O Lucro Presumido \u00e9 um regime de tributa\u00e7\u00e3o simplificado que utiliza margens fixas de presun\u00e7\u00e3o para calcular a base do IRPJ e da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,47,48,5],"tags":[],"class_list":["post-1303","post","type-post","status-publish","format-standard","hentry","category-contabilidade","category-csll","category-irpj","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1303"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1303\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}