{"id":1324,"date":"2025-08-26T19:45:10","date_gmt":"2025-08-26T22:45:10","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/08\/26\/carf-aprova-seis-novas-sumulas-em-sessao-unanime-confira-decisoes\/"},"modified":"2025-08-26T19:45:10","modified_gmt":"2025-08-26T22:45:10","slug":"carf-aprova-seis-novas-sumulas-em-sessao-unanime-confira-decisoes","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/08\/26\/carf-aprova-seis-novas-sumulas-em-sessao-unanime-confira-decisoes\/","title":{"rendered":"CARF aprova seis novas s\u00famulas em sess\u00e3o un\u00e2nime; confira decis\u00f5es"},"content":{"rendered":"<div>\n<p>O Conselho Administrativo de Recursos Fiscais (CARF) aprovou, em 20 de agosto de 2025, seis novos enunciados de s\u00famulas durante sess\u00e3o extraordin\u00e1ria. A decis\u00e3o foi un\u00e2nime e tem como objetivo fortalecer a seguran\u00e7a jur\u00eddica, acelerar julgamentos e reduzir o estoque de processos administrativos fiscais. Com a aprova\u00e7\u00e3o, as s\u00famulas do CARF passam a vincular n\u00e3o [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/08\/26\/carf-aprova-seis-novas-sumulas-em-sessao-unanime-confira-decisoes\/\">CARF aprova seis novas s\u00famulas em sess\u00e3o un\u00e2nime; confira decis\u00f5es<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Administrativo de Recursos Fiscais (CARF) aprovou, em 20 de agosto de 2025, seis novos enunciados de s\u00famulas durante sess\u00e3o extraordin\u00e1ria. A decis\u00e3o foi un\u00e2nime e tem como objetivo fortalecer a seguran\u00e7a jur\u00eddica, acelerar julgamentos e reduzir o estoque de processos administrativos fiscais. Com a aprova\u00e7\u00e3o, as s\u00famulas do CARF passam a vincular n\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,23,5],"tags":[],"class_list":["post-1324","post","type-post","status-publish","format-standard","hentry","category-carf","category-irpf","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1324"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1324\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}