{"id":1346,"date":"2025-09-01T20:49:31","date_gmt":"2025-09-01T23:49:31","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/09\/01\/stf-barra-cobranca-retroativa-de-icms-sobre-transferencia-de-mercadorias\/"},"modified":"2025-09-01T20:49:31","modified_gmt":"2025-09-01T23:49:31","slug":"stf-barra-cobranca-retroativa-de-icms-sobre-transferencia-de-mercadorias","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/09\/01\/stf-barra-cobranca-retroativa-de-icms-sobre-transferencia-de-mercadorias\/","title":{"rendered":"STF barra cobran\u00e7a retroativa de ICMS sobre transfer\u00eancia de mercadorias"},"content":{"rendered":"<div>\n<p>Por 8 votos a 3, o Supremo Tribunal Federal (STF) decidiu que a modula\u00e7\u00e3o de efeitos estabelecida na ADC 49 n\u00e3o permite a cobran\u00e7a retroativa de ICMS sobre contribuintes que deixaram de recolher o imposto em transfer\u00eancias de mercadorias entre empresas do mesmo grupo antes de 2024. Por meio da ADC 49 os ministros declararam [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/09\/01\/stf-barra-cobranca-retroativa-de-icms-sobre-transferencia-de-mercadorias\/\">STF barra cobran\u00e7a retroativa de ICMS sobre transfer\u00eancia de mercadorias<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por 8 votos a 3, o Supremo Tribunal Federal (STF) decidiu que a modula\u00e7\u00e3o de efeitos estabelecida na ADC 49 n\u00e3o permite a cobran\u00e7a retroativa de ICMS sobre contribuintes que deixaram de recolher o imposto em transfer\u00eancias de mercadorias entre empresas do mesmo grupo antes de 2024. Por meio da ADC 49 os ministros declararam [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,10,80],"tags":[],"class_list":["post-1346","post","type-post","status-publish","format-standard","hentry","category-economia","category-icms","category-stf","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1346"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1346\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}