{"id":1361,"date":"2025-09-04T23:09:39","date_gmt":"2025-09-05T02:09:39","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/09\/04\/cfc-lanca-pesquisa-para-atualizar-o-perfil-do-profissional-da-contabilidade\/"},"modified":"2025-09-04T23:09:39","modified_gmt":"2025-09-05T02:09:39","slug":"cfc-lanca-pesquisa-para-atualizar-o-perfil-do-profissional-da-contabilidade","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/09\/04\/cfc-lanca-pesquisa-para-atualizar-o-perfil-do-profissional-da-contabilidade\/","title":{"rendered":"CFC lan\u00e7a pesquisa para atualizar o Perfil do Profissional da Contabilidade"},"content":{"rendered":"<div>\n<p>O Conselho Federal de Contabilidade (CFC) lan\u00e7ou, em parceria com a Funda\u00e7\u00e3o Getulio Vargas (FGV), a edi\u00e7\u00e3o 2025 da pesquisa Perfil do Profissional da Contabilidade, um levantamento que tem como objetivo conhecer as principais caracter\u00edsticas dos contadores e t\u00e9cnicos em contabilidade registrados no Sistema CFC\/CRCs. A iniciativa busca compreender melhor a realidade da classe cont\u00e1bil, [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/09\/04\/cfc-lanca-pesquisa-para-atualizar-o-perfil-do-profissional-da-contabilidade\/\">CFC lan\u00e7a pesquisa para atualizar o Perfil do Profissional da Contabilidade<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Federal de Contabilidade (CFC) lan\u00e7ou, em parceria com a Funda\u00e7\u00e3o Getulio Vargas (FGV), a edi\u00e7\u00e3o 2025 da pesquisa Perfil do Profissional da Contabilidade, um levantamento que tem como objetivo conhecer as principais caracter\u00edsticas dos contadores e t\u00e9cnicos em contabilidade registrados no Sistema CFC\/CRCs. A iniciativa busca compreender melhor a realidade da classe cont\u00e1bil, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-1361","post","type-post","status-publish","format-standard","hentry","category-contabilidade","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1361"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1361\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}