{"id":1377,"date":"2025-09-10T21:32:54","date_gmt":"2025-09-11T00:32:54","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/09\/10\/bernard-appy-analisa-impactos-das-novas-regras-de-tributacao-no-setor-de-cooperativas\/"},"modified":"2025-09-10T21:32:54","modified_gmt":"2025-09-11T00:32:54","slug":"bernard-appy-analisa-impactos-das-novas-regras-de-tributacao-no-setor-de-cooperativas","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/09\/10\/bernard-appy-analisa-impactos-das-novas-regras-de-tributacao-no-setor-de-cooperativas\/","title":{"rendered":"Bernard Appy analisa impactos das novas regras de tributa\u00e7\u00e3o no setor de cooperativas"},"content":{"rendered":"<div>\n<p>Um sistema tribut\u00e1rio neutro \u00e9 positivo para o pa\u00eds porque evita distor\u00e7\u00f5es na organiza\u00e7\u00e3o da atividade econ\u00f4mica e beneficia quem \u00e9 mais eficiente, ressaltou na ter\u00e7a-feira (9\/9) o secret\u00e1rio extraordin\u00e1rio da Reforma Tribut\u00e1ria, Bernard Appy. Ele participou de um painel sobre a Reforma Tribut\u00e1ria no 5\u00ba Semin\u00e1rio Jur\u00eddico do Sistema OCB \u2012 Direito Cooperativo em [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/09\/10\/bernard-appy-analisa-impactos-das-novas-regras-de-tributacao-no-setor-de-cooperativas\/\">Bernard Appy analisa impactos das novas regras de tributa\u00e7\u00e3o no setor de cooperativas<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um sistema tribut\u00e1rio neutro \u00e9 positivo para o pa\u00eds porque evita distor\u00e7\u00f5es na organiza\u00e7\u00e3o da atividade econ\u00f4mica e beneficia quem \u00e9 mais eficiente, ressaltou na ter\u00e7a-feira (9\/9) o secret\u00e1rio extraordin\u00e1rio da Reforma Tribut\u00e1ria, Bernard Appy. Ele participou de um painel sobre a Reforma Tribut\u00e1ria no 5\u00ba Semin\u00e1rio Jur\u00eddico do Sistema OCB \u2012 Direito Cooperativo em [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,5],"tags":[],"class_list":["post-1377","post","type-post","status-publish","format-standard","hentry","category-reforma-tributaria","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1377"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1377\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}