{"id":1399,"date":"2025-09-17T17:29:11","date_gmt":"2025-09-17T20:29:11","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/09\/17\/senado-propoe-projeto-alternativo-para-isencao-do-ir-com-menos-restricoes-e-calendario-enxuto\/"},"modified":"2025-09-17T17:29:11","modified_gmt":"2025-09-17T20:29:11","slug":"senado-propoe-projeto-alternativo-para-isencao-do-ir-com-menos-restricoes-e-calendario-enxuto","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/09\/17\/senado-propoe-projeto-alternativo-para-isencao-do-ir-com-menos-restricoes-e-calendario-enxuto\/","title":{"rendered":"Senado prop\u00f5e projeto alternativo para isen\u00e7\u00e3o do IR com menos restri\u00e7\u00f5es e calend\u00e1rio enxuto"},"content":{"rendered":"<div>\n<p>O senador Renan Calheiros (MDB-AL) anunciou nesta ter\u00e7a-feira (16) que ser\u00e1 o relator de um novo projeto no Senado que isenta do Imposto de Renda (IR) pessoas que ganham at\u00e9 R$ 5.000 por m\u00eas, oferecendo uma vers\u00e3o alternativa \u00e0quela em discuss\u00e3o atualmente. Ele lidera essa iniciativa como presidente da Comiss\u00e3o de Assuntos Econ\u00f4micos (CAE) e [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/09\/17\/rojeto-alternativo-para-isencao-do-ir-com-menos-restricoes-e-calendario-enxuto\/\">Senado prop\u00f5e projeto alternativo para isen\u00e7\u00e3o do IR com menos restri\u00e7\u00f5es e calend\u00e1rio enxuto<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O senador Renan Calheiros (MDB-AL) anunciou nesta ter\u00e7a-feira (16) que ser\u00e1 o relator de um novo projeto no Senado que isenta do Imposto de Renda (IR) pessoas que ganham at\u00e9 R$ 5.000 por m\u00eas, oferecendo uma vers\u00e3o alternativa \u00e0quela em discuss\u00e3o atualmente. Ele lidera essa iniciativa como presidente da Comiss\u00e3o de Assuntos Econ\u00f4micos (CAE) e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-1399","post","type-post","status-publish","format-standard","hentry","category-ir","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1399"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1399\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}