{"id":1424,"date":"2025-09-25T18:45:56","date_gmt":"2025-09-25T21:45:56","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/09\/25\/tj-ro-nega-penhora-de-aposentadoria-de-idoso-para-pagar-divida-fiscal\/"},"modified":"2025-09-25T18:45:56","modified_gmt":"2025-09-25T21:45:56","slug":"tj-ro-nega-penhora-de-aposentadoria-de-idoso-para-pagar-divida-fiscal","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/09\/25\/tj-ro-nega-penhora-de-aposentadoria-de-idoso-para-pagar-divida-fiscal\/","title":{"rendered":"TJ-RO nega penhora de aposentadoria de idoso para pagar d\u00edvida fiscal"},"content":{"rendered":"<div>\n<p>Os julgadores da 1\u00aa C\u00e2mara Especial do Tribunal de Justi\u00e7a de Rond\u00f4nia confirmaram uma decis\u00e3o do ju\u00edzo de primeiro grau que negou ao estado de Rond\u00f4nia a penhora de 10% sobre aposentadoria de um homem idoso, que recebe o equivalente a um sal\u00e1rio m\u00ednimo. Renda insuficiente para cobrir as necessidades b\u00e1sicas de subsist\u00eancia do aposentado. [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/09\/25\/tj-ro-nega-penhora-de-aposentadoria-de-idoso-para-pagar-divida-fiscal\/\">TJ-RO nega penhora de aposentadoria de idoso para pagar d\u00edvida fiscal<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Os julgadores da 1\u00aa C\u00e2mara Especial do Tribunal de Justi\u00e7a de Rond\u00f4nia confirmaram uma decis\u00e3o do ju\u00edzo de primeiro grau que negou ao estado de Rond\u00f4nia a penhora de 10% sobre aposentadoria de um homem idoso, que recebe o equivalente a um sal\u00e1rio m\u00ednimo. Renda insuficiente para cobrir as necessidades b\u00e1sicas de subsist\u00eancia do aposentado. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-1424","post","type-post","status-publish","format-standard","hentry","category-fisco","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1424"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1424\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}