{"id":1443,"date":"2025-10-02T22:11:37","date_gmt":"2025-10-03T01:11:37","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/10\/02\/esocial-disponibiliza-no-ambiente-de-testes-validacao-do-emprestimo-consignado-do-programa-credito-do-trabalhador\/"},"modified":"2025-10-02T22:11:37","modified_gmt":"2025-10-03T01:11:37","slug":"esocial-disponibiliza-no-ambiente-de-testes-validacao-do-emprestimo-consignado-do-programa-credito-do-trabalhador","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/10\/02\/esocial-disponibiliza-no-ambiente-de-testes-validacao-do-emprestimo-consignado-do-programa-credito-do-trabalhador\/","title":{"rendered":"eSocial disponibiliza, no ambiente de testes, valida\u00e7\u00e3o do empr\u00e9stimo consignado do Programa Cr\u00e9dito do Trabalhador"},"content":{"rendered":"<div>\n<p>No dia 01\/10\/2025, foi publicada, no ambiente de produ\u00e7\u00e3o restrita, uma vers\u00e3o do sistema com uma nova valida\u00e7\u00e3o relativa ao empr\u00e9stimo consignado, vinculado ao Programa Cr\u00e9dito do Trabalhador. Com a nova valida\u00e7\u00e3o, ao receber eventos de remunera\u00e7\u00e3o (S-1200 \/ S-2299 \/ S-2399), o eSocial verificar\u00e1 se o v\u00ednculo possui contrato de empr\u00e9stimo consignado, com parcela [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/10\/02\/esocial-disponibiliza-no-ambiente-de-testes-validacao-emprestimo-consignado-programa-credito-do-trabalhador\/\">eSocial disponibiliza, no ambiente de testes, valida\u00e7\u00e3o do empr\u00e9stimo consignado do Programa Cr\u00e9dito do Trabalhador<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>No dia 01\/10\/2025, foi publicada, no ambiente de produ\u00e7\u00e3o restrita, uma vers\u00e3o do sistema com uma nova valida\u00e7\u00e3o relativa ao empr\u00e9stimo consignado, vinculado ao Programa Cr\u00e9dito do Trabalhador. Com a nova valida\u00e7\u00e3o, ao receber eventos de remunera\u00e7\u00e3o (S-1200 \/ S-2299 \/ S-2399), o eSocial verificar\u00e1 se o v\u00ednculo possui contrato de empr\u00e9stimo consignado, com parcela [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[233,20,234,14],"tags":[],"class_list":["post-1443","post","type-post","status-publish","format-standard","hentry","category-dataprev","category-esocial","category-programa-credito-do-trabalhador","category-sped","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1443"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1443\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}