{"id":1467,"date":"2025-10-10T00:07:50","date_gmt":"2025-10-10T03:07:50","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/10\/10\/carf-nao-conhece-recurso-e-mantem-deducao-de-acordo-de-leniencia-do-irpj-e-csll\/"},"modified":"2025-10-10T00:07:50","modified_gmt":"2025-10-10T03:07:50","slug":"carf-nao-conhece-recurso-e-mantem-deducao-de-acordo-de-leniencia-do-irpj-e-csll","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/10\/10\/carf-nao-conhece-recurso-e-mantem-deducao-de-acordo-de-leniencia-do-irpj-e-csll\/","title":{"rendered":"Carf n\u00e3o conhece recurso e mant\u00e9m dedu\u00e7\u00e3o de acordo de leni\u00eancia do IRPJ e CSLL"},"content":{"rendered":"<div>\n<p>A 1\u00aa Turma da C\u00e2mara Superior n\u00e3o conheceu do recurso da Fazenda Nacional frente \u00e0 decis\u00e3o da turma ordin\u00e1ria que permitiu a dedu\u00e7\u00e3o de multas relacionadas a acordo de leni\u00eancia do IRPJ e da CSLL. Com isso, ficou mantido o entendimento da turma ordin\u00e1ria de que o acordo de leni\u00eancia constitui ato jur\u00eddico leg\u00edtimo e [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/10\/08\/carf-nao-conhece-recurso-e-mantem-deducao-de-acordo-de-leniencia-do-irpj-e-csll\/\">Carf n\u00e3o conhece recurso e mant\u00e9m dedu\u00e7\u00e3o de acordo de leni\u00eancia do IRPJ e CSLL<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A 1\u00aa Turma da C\u00e2mara Superior n\u00e3o conheceu do recurso da Fazenda Nacional frente \u00e0 decis\u00e3o da turma ordin\u00e1ria que permitiu a dedu\u00e7\u00e3o de multas relacionadas a acordo de leni\u00eancia do IRPJ e da CSLL. Com isso, ficou mantido o entendimento da turma ordin\u00e1ria de que o acordo de leni\u00eancia constitui ato jur\u00eddico leg\u00edtimo e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,47,48,5],"tags":[],"class_list":["post-1467","post","type-post","status-publish","format-standard","hentry","category-carf","category-csll","category-irpj","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1467"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1467\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}