{"id":1473,"date":"2025-10-13T00:41:56","date_gmt":"2025-10-13T03:41:56","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/10\/13\/receita-federal-regulamenta-parcelamento-excepcional-de-debitos-previdenciarios-de-municipios-e-consorcios-publicos\/"},"modified":"2025-10-13T00:41:56","modified_gmt":"2025-10-13T03:41:56","slug":"receita-federal-regulamenta-parcelamento-excepcional-de-debitos-previdenciarios-de-municipios-e-consorcios-publicos","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/10\/13\/receita-federal-regulamenta-parcelamento-excepcional-de-debitos-previdenciarios-de-municipios-e-consorcios-publicos\/","title":{"rendered":"Receita Federal regulamenta parcelamento excepcional de d\u00e9bitos previdenci\u00e1rios de munic\u00edpios e cons\u00f3rcios p\u00fablicos"},"content":{"rendered":"<div>\n<p>A Receita Federal publicou a Instru\u00e7\u00e3o Normativa n\u00ba 2283\/2025, que regulamenta o parcelamento excepcional de d\u00e9bitos previdenci\u00e1rios dos munic\u00edpios, suas autarquias e funda\u00e7\u00f5es, e dos cons\u00f3rcios p\u00fablicos intermunicipais. A medida foi viabilizada pela Emenda Constitucional n\u00ba 136, de 9 de setembro de 2025 e contribuir\u00e1 para a promo\u00e7\u00e3o da conformidade fiscal e o fortalecimento da [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/10\/12\/receita-federal-regulamenta-parcelamento-excepcional-de-debitos-previdenciarios-de-municipios-e-consorcios-publicos\/\">Receita Federal regulamenta parcelamento excepcional de d\u00e9bitos previdenci\u00e1rios de munic\u00edpios e cons\u00f3rcios p\u00fablicos<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Receita Federal publicou a Instru\u00e7\u00e3o Normativa n\u00ba 2283\/2025, que regulamenta o parcelamento excepcional de d\u00e9bitos previdenci\u00e1rios dos munic\u00edpios, suas autarquias e funda\u00e7\u00f5es, e dos cons\u00f3rcios p\u00fablicos intermunicipais. A medida foi viabilizada pela Emenda Constitucional n\u00ba 136, de 9 de setembro de 2025 e contribuir\u00e1 para a promo\u00e7\u00e3o da conformidade fiscal e o fortalecimento da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-1473","post","type-post","status-publish","format-standard","hentry","category-economia","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1473"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1473\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}