{"id":1504,"date":"2025-10-20T21:48:21","date_gmt":"2025-10-21T00:48:21","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/10\/20\/cni-aciona-stf-contra-cobrancas-retroativas-de-tributos-apos-novo-entendimento-do-carf\/"},"modified":"2025-10-20T21:48:21","modified_gmt":"2025-10-21T00:48:21","slug":"cni-aciona-stf-contra-cobrancas-retroativas-de-tributos-apos-novo-entendimento-do-carf","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/10\/20\/cni-aciona-stf-contra-cobrancas-retroativas-de-tributos-apos-novo-entendimento-do-carf\/","title":{"rendered":"CNI aciona STF contra cobran\u00e7as retroativas de tributos ap\u00f3s novo entendimento do Carf"},"content":{"rendered":"<div>\n<p>A Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI) acionou o Supremo Tribunal Federal (STF) para contestar uma s\u00famula do Conselho Administrativo de Recursos Fiscais (Carf) que autoriza a revis\u00e3o de cobran\u00e7as tribut\u00e1rias antigas com base em interpreta\u00e7\u00f5es mais recentes do \u00f3rg\u00e3o. A Argui\u00e7\u00e3o de Descumprimento de Preceito Fundamental (ADPF) 1276 foi distribu\u00edda ao ministro Luiz Fux. Cobran\u00e7a [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/10\/20\/cni-aciona-stf-contra-cobrancas-retroativas-tributos-novo-entendimento-carf\/\">CNI aciona STF contra cobran\u00e7as retroativas de tributos ap\u00f3s novo entendimento do Carf<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI) acionou o Supremo Tribunal Federal (STF) para contestar uma s\u00famula do Conselho Administrativo de Recursos Fiscais (Carf) que autoriza a revis\u00e3o de cobran\u00e7as tribut\u00e1rias antigas com base em interpreta\u00e7\u00f5es mais recentes do \u00f3rg\u00e3o. A Argui\u00e7\u00e3o de Descumprimento de Preceito Fundamental (ADPF) 1276 foi distribu\u00edda ao ministro Luiz Fux. Cobran\u00e7a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,5],"tags":[],"class_list":["post-1504","post","type-post","status-publish","format-standard","hentry","category-carf","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1504"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1504\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}