{"id":1585,"date":"2025-11-11T20:49:07","date_gmt":"2025-11-11T23:49:07","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/11\/11\/reforma-tributaria-comsefaz-e-comite-gestor-do-ibs-debatem-metodologia-de-calculo-da-aliquota-de-referencia-da-cbs-em-evento-do-tcu\/"},"modified":"2025-11-11T20:49:07","modified_gmt":"2025-11-11T23:49:07","slug":"reforma-tributaria-comsefaz-e-comite-gestor-do-ibs-debatem-metodologia-de-calculo-da-aliquota-de-referencia-da-cbs-em-evento-do-tcu","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/11\/11\/reforma-tributaria-comsefaz-e-comite-gestor-do-ibs-debatem-metodologia-de-calculo-da-aliquota-de-referencia-da-cbs-em-evento-do-tcu\/","title":{"rendered":"Reforma tribut\u00e1ria: Comsefaz e Comit\u00ea Gestor do IBS debatem metodologia de c\u00e1lculo da al\u00edquota de refer\u00eancia da CBS em evento do TCU"},"content":{"rendered":"<div>\n<p>O Comsefaz participou, nesta segunda-feira (10), do painel da Reforma Tribut\u00e1ria \u2013 Metodologia de C\u00e1lculo da Al\u00edquota de Refer\u00eancia da CBS, promovido pelo Tribunal de Contas da Uni\u00e3o. O evento ocorreu no plenarinho do Instituto Serzedello Corr\u00eaa (ISC), em Bras\u00edlia, e contou com o apoio da Receita Federal do Brasil. O auditor fiscal da secretaria [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/11\/11\/reforma-tributaria-comsefaz-e-comite-gestor-do-ibs-debatem-metodologia-de-calculo-da-aliquota-de-referencia-da-cbs-em-evento-do-tcu\/\">Reforma tribut\u00e1ria: Comsefaz e Comit\u00ea Gestor do IBS debatem metodologia de c\u00e1lculo da al\u00edquota de refer\u00eancia da CBS em evento do TCU<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Comsefaz participou, nesta segunda-feira (10), do painel da Reforma Tribut\u00e1ria \u2013 Metodologia de C\u00e1lculo da Al\u00edquota de Refer\u00eancia da CBS, promovido pelo Tribunal de Contas da Uni\u00e3o. O evento ocorreu no plenarinho do Instituto Serzedello Corr\u00eaa (ISC), em Bras\u00edlia, e contou com o apoio da Receita Federal do Brasil. O auditor fiscal da secretaria [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-1585","post","type-post","status-publish","format-standard","hentry","category-reforma-tributaria","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1585"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1585\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}