{"id":1587,"date":"2025-11-12T22:30:27","date_gmt":"2025-11-13T01:30:27","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/11\/12\/mais-de-3-mil-empresas-poderao-ser-excluidas-do-simples-nacional-se-nao-regularizarem-debitos-no-rs\/"},"modified":"2025-11-12T22:30:27","modified_gmt":"2025-11-13T01:30:27","slug":"mais-de-3-mil-empresas-poderao-ser-excluidas-do-simples-nacional-se-nao-regularizarem-debitos-no-rs","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/11\/12\/mais-de-3-mil-empresas-poderao-ser-excluidas-do-simples-nacional-se-nao-regularizarem-debitos-no-rs\/","title":{"rendered":"Mais de 3 mil empresas poder\u00e3o ser exclu\u00eddas do Simples Nacional se n\u00e3o regularizarem d\u00e9bitos no RS"},"content":{"rendered":"<div>\n<p>Cerca de 3,1 mil empresas ga\u00fachas optantes pelo Simples Nacional que apresentam d\u00e9bitos sem exigibilidade suspensa perante a Receita Estadual poder\u00e3o ser exclu\u00eddas do regime de tributa\u00e7\u00e3o simplificado. Os contribuintes nessa situa\u00e7\u00e3o est\u00e3o sendo notificados pelo fisco ga\u00facho e podem consultar eventuais pend\u00eancias no Portal e-CAC (Centro de Atendimento Virtual ao Contribuinte) ou pelo aplicativo [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/11\/12\/mais-de-3-mil-empresas-excluidas-do-simples-nacional-se-nao-regularizarem-debitos-no-rs\/\">Mais de 3 mil empresas poder\u00e3o ser exclu\u00eddas do Simples Nacional se n\u00e3o regularizarem d\u00e9bitos no RS<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cerca de 3,1 mil empresas ga\u00fachas optantes pelo Simples Nacional que apresentam d\u00e9bitos sem exigibilidade suspensa perante a Receita Estadual poder\u00e3o ser exclu\u00eddas do regime de tributa\u00e7\u00e3o simplificado. Os contribuintes nessa situa\u00e7\u00e3o est\u00e3o sendo notificados pelo fisco ga\u00facho e podem consultar eventuais pend\u00eancias no Portal e-CAC (Centro de Atendimento Virtual ao Contribuinte) ou pelo aplicativo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,30],"tags":[],"class_list":["post-1587","post","type-post","status-publish","format-standard","hentry","category-sefaz","category-simples-nacional","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1587"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1587\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}