{"id":1595,"date":"2025-11-13T23:15:54","date_gmt":"2025-11-14T02:15:54","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/11\/13\/o-efeito-do-simples-nacional-na-cadeia-de-fornecimento\/"},"modified":"2025-11-13T23:15:54","modified_gmt":"2025-11-14T02:15:54","slug":"o-efeito-do-simples-nacional-na-cadeia-de-fornecimento","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/11\/13\/o-efeito-do-simples-nacional-na-cadeia-de-fornecimento\/","title":{"rendered":"O efeito do Simples Nacional na cadeia de fornecimento"},"content":{"rendered":"<div>\n<p>Ol\u00e1 amigos e amigas. \u00c9 sempre um prazer falar e escrever para as pessoas que est\u00e3o neste mundo tribut\u00e1rio e tem nas ferramentas tecnol\u00f3gicas seu dia a dia. Uma discuss\u00e3o muito acalorada nos \u00faltimos dias \u00e9 sobre a possibilidade de cr\u00e9ditos tribut\u00e1rios de IVA Dual (IBS\/CBS) para os contribuintes do regime do Simples Nacional. H\u00e1 [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/11\/13\/o-efeito-do-simples-nacional-na-cadeia-de-fornecimento\/\">O efeito do Simples Nacional na cadeia de fornecimento<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1 amigos e amigas. \u00c9 sempre um prazer falar e escrever para as pessoas que est\u00e3o neste mundo tribut\u00e1rio e tem nas ferramentas tecnol\u00f3gicas seu dia a dia. Uma discuss\u00e3o muito acalorada nos \u00faltimos dias \u00e9 sobre a possibilidade de cr\u00e9ditos tribut\u00e1rios de IVA Dual (IBS\/CBS) para os contribuintes do regime do Simples Nacional. H\u00e1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,16,54],"tags":[],"class_list":["post-1595","post","type-post","status-publish","format-standard","hentry","category-artigos","category-escritos-por-mauro-negruni","category-eventos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1595"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1595\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}