{"id":1610,"date":"2025-11-19T22:20:23","date_gmt":"2025-11-20T01:20:23","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/11\/19\/reforma-tributaria-avanca-com-testes-de-novos-documentos-fiscais-para-os-setores-de-saneamento-e-transporte-aereo\/"},"modified":"2025-11-19T22:20:23","modified_gmt":"2025-11-20T01:20:23","slug":"reforma-tributaria-avanca-com-testes-de-novos-documentos-fiscais-para-os-setores-de-saneamento-e-transporte-aereo","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/11\/19\/reforma-tributaria-avanca-com-testes-de-novos-documentos-fiscais-para-os-setores-de-saneamento-e-transporte-aereo\/","title":{"rendered":"Reforma tribut\u00e1ria avan\u00e7a com testes de novos documentos fiscais para os setores de saneamento e transporte a\u00e9reo"},"content":{"rendered":"<div>\n<p>A reforma tribut\u00e1ria do consumo avan\u00e7a com mais um passo importante na moderniza\u00e7\u00e3o dos documentos fiscais eletr\u00f4nicos. A Sefaz Virtual do Rio Grande do Sul (SVRS) liberou dois novos ambientes de autoriza\u00e7\u00e3o que integram diretamente a implementa\u00e7\u00e3o do novo modelo tribut\u00e1rio: a Nota Fiscal de \u00c1gua e Saneamento Eletr\u00f4nica (NFAg) e o Bilhete de Passagem [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/11\/19\/reforma-tributaria-avanca-com-testes-de-novos-documentos-fiscais-para-os-setores-de-saneamento-e-transporte-aereo\/\">Reforma tribut\u00e1ria avan\u00e7a com testes de novos documentos fiscais para os setores de saneamento e transporte a\u00e9reo<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A reforma tribut\u00e1ria do consumo avan\u00e7a com mais um passo importante na moderniza\u00e7\u00e3o dos documentos fiscais eletr\u00f4nicos. A Sefaz Virtual do Rio Grande do Sul (SVRS) liberou dois novos ambientes de autoriza\u00e7\u00e3o que integram diretamente a implementa\u00e7\u00e3o do novo modelo tribut\u00e1rio: a Nota Fiscal de \u00c1gua e Saneamento Eletr\u00f4nica (NFAg) e o Bilhete de Passagem [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-1610","post","type-post","status-publish","format-standard","hentry","category-reforma-tributaria","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1610"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1610\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}