{"id":1631,"date":"2025-11-25T20:54:42","date_gmt":"2025-11-25T23:54:42","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/11\/25\/publicacao-da-nota-tecnica-2025-002-v-1-32\/"},"modified":"2025-11-25T20:54:42","modified_gmt":"2025-11-25T23:54:42","slug":"publicacao-da-nota-tecnica-2025-002-v-1-32","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/11\/25\/publicacao-da-nota-tecnica-2025-002-v-1-32\/","title":{"rendered":"Publica\u00e7\u00e3o da Nota T\u00e9cnica 2025.002 v.1.32"},"content":{"rendered":"<div>\n<p>Nota t\u00e9cnica de adequa\u00e7\u00e3o dos leiautes da NF-e e da NFC-e para inclus\u00e3o dos campos e das regras de valida\u00e7\u00e3o referentes \u00e0 Reforma Tribut\u00e1ria do Consumo \u2013 RTC. Acesse o Portal da Nota Fiscal Eletr\u00f4nica para fazer o download da nota t\u00e9cnica. Fonte: Portal NF-e<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/11\/25\/publicacao-da-nota-tecnica-2025-002-v-1-32\/\">Publica\u00e7\u00e3o da Nota T\u00e9cnica 2025.002 v.1.32<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nota t\u00e9cnica de adequa\u00e7\u00e3o dos leiautes da NF-e e da NFC-e para inclus\u00e3o dos campos e das regras de valida\u00e7\u00e3o referentes \u00e0 Reforma Tribut\u00e1ria do Consumo \u2013 RTC. Acesse o Portal da Nota Fiscal Eletr\u00f4nica para fazer o download da nota t\u00e9cnica. Fonte: Portal NF-e O post Publica\u00e7\u00e3o da Nota T\u00e9cnica 2025.002 v.1.32 apareceu primeiro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-1631","post","type-post","status-publish","format-standard","hentry","category-nota-fiscal-eletronica-nf-e","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1631"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1631\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}