{"id":1651,"date":"2025-12-02T20:58:33","date_gmt":"2025-12-02T23:58:33","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/02\/repetitivo-do-stj-traz-julgados-sobre-deducao-dos-jcp-extemporaneos-no-irpj-e-na-csll\/"},"modified":"2025-12-02T20:58:33","modified_gmt":"2025-12-02T23:58:33","slug":"repetitivo-do-stj-traz-julgados-sobre-deducao-dos-jcp-extemporaneos-no-irpj-e-na-csll","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/02\/repetitivo-do-stj-traz-julgados-sobre-deducao-dos-jcp-extemporaneos-no-irpj-e-na-csll\/","title":{"rendered":"Repetitivo do STJ traz julgados sobre dedu\u00e7\u00e3o dos JCP extempor\u00e2neos no IRPJ e na CSLL"},"content":{"rendered":"<div>\n<p>A Secretaria de Jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a (STJ) atualizou a base de dados de Repetitivos e IACs Anotados. Foram inclu\u00eddas informa\u00e7\u00f5es a respeito do julgamento dos Recursos Especiais 2.161.414, 2.162.248, 2.162.629 e 2.163.735, classificados no ramo do direito tribut\u00e1rio, no assunto Contribui\u00e7\u00e3o Social sobre o Lucro L\u00edquido (CSLL) e Imposto de Renda. Os [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/12\/02\/repetitivo-do-stj-traz-julgados-sobre-deducao-dos-jcp-extemporaneos-no-irpj-e-na-csll\/\">Repetitivo do STJ traz julgados sobre dedu\u00e7\u00e3o dos JCP extempor\u00e2neos no IRPJ e na CSLL<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a (STJ) atualizou a base de dados de Repetitivos e IACs Anotados. Foram inclu\u00eddas informa\u00e7\u00f5es a respeito do julgamento dos Recursos Especiais 2.161.414, 2.162.248, 2.162.629 e 2.163.735, classificados no ramo do direito tribut\u00e1rio, no assunto Contribui\u00e7\u00e3o Social sobre o Lucro L\u00edquido (CSLL) e Imposto de Renda. Os [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,47,146,48],"tags":[],"class_list":["post-1651","post","type-post","status-publish","format-standard","hentry","category-contabilidade","category-csll","category-direito-tributario","category-irpj","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1651"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1651\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}