{"id":1662,"date":"2025-12-07T21:46:21","date_gmt":"2025-12-08T00:46:21","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/07\/receita-federal-organiza-evento-de-lancamento-do-programa-de-conformidade-cooperativa-fiscal-da-receita-federal-confia\/"},"modified":"2025-12-07T21:46:21","modified_gmt":"2025-12-08T00:46:21","slug":"receita-federal-organiza-evento-de-lancamento-do-programa-de-conformidade-cooperativa-fiscal-da-receita-federal-confia","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/07\/receita-federal-organiza-evento-de-lancamento-do-programa-de-conformidade-cooperativa-fiscal-da-receita-federal-confia\/","title":{"rendered":"Receita Federal organiza evento de Lan\u00e7amento do Programa de Conformidade Cooperativa Fiscal da Receita Federal (Confia)"},"content":{"rendered":"<div>\n<p>A Receita Federal est\u00e1 organizando o evento de Lan\u00e7amento do Programa de Conformidade Cooperativa Fiscal da Receita Federal (Confia), a ser realizado em 9 de dezembro, das 8h30 \u00e0s 18h. O evento, que tamb\u00e9m ser\u00e1 transmitido ao vivo pelo Canal da Receita Federal no YouTube em portugu\u00eas, ingl\u00eas e espanhol, marcar\u00e1 a consolida\u00e7\u00e3o do Programa [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/12\/07\/receita-federal-organiza-evento-de-lancamento-do-programa-de-conformidade-cooperativa-fiscal-da-receita-federal-confia\/\">Receita Federal organiza evento de Lan\u00e7amento do Programa de Conformidade Cooperativa Fiscal da Receita Federal (Confia)<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Receita Federal est\u00e1 organizando o evento de Lan\u00e7amento do Programa de Conformidade Cooperativa Fiscal da Receita Federal (Confia), a ser realizado em 9 de dezembro, das 8h30 \u00e0s 18h. O evento, que tamb\u00e9m ser\u00e1 transmitido ao vivo pelo Canal da Receita Federal no YouTube em portugu\u00eas, ingl\u00eas e espanhol, marcar\u00e1 a consolida\u00e7\u00e3o do Programa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1662","post","type-post","status-publish","format-standard","hentry","category-rfb","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1662"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1662\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}