{"id":1666,"date":"2025-12-07T22:02:45","date_gmt":"2025-12-08T01:02:45","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/07\/efd-contribuicoes-versao-corretiva-6-1-1\/"},"modified":"2025-12-07T22:02:45","modified_gmt":"2025-12-08T01:02:45","slug":"efd-contribuicoes-versao-corretiva-6-1-1","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/07\/efd-contribuicoes-versao-corretiva-6-1-1\/","title":{"rendered":"EFD-CONTRIBUI\u00c7\u00d5ES \u2013 Vers\u00e3o corretiva 6.1.1"},"content":{"rendered":"<div>\n<p>A vers\u00e3o 6.1.0 do Programa Gerador de Escritura\u00e7\u00e3o \u2013 PGE da EFD Contribui\u00e7\u00f5es apresentou erro na funcionalidade do campo Incri\u00e7\u00e3o Estadual \u2013 IE, dos registros 0140 e 0150. Esse erro foi corrigido nesta vers\u00e3o 6.1.1 Recomenda-se realizar a C\u00f3pia de Seguran\u00e7a de todas as escritura\u00e7\u00f5es contidas na base de dados, antes de instalar uma nova [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/12\/07\/efd-contribuicoes-versao-corretiva-6-1-1\/\">EFD-CONTRIBUI\u00c7\u00d5ES \u2013 Vers\u00e3o corretiva 6.1.1<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A vers\u00e3o 6.1.0 do Programa Gerador de Escritura\u00e7\u00e3o \u2013 PGE da EFD Contribui\u00e7\u00f5es apresentou erro na funcionalidade do campo Incri\u00e7\u00e3o Estadual \u2013 IE, dos registros 0140 e 0150. Esse erro foi corrigido nesta vers\u00e3o 6.1.1 Recomenda-se realizar a C\u00f3pia de Seguran\u00e7a de todas as escritura\u00e7\u00f5es contidas na base de dados, antes de instalar uma nova [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,269],"tags":[],"class_list":["post-1666","post","type-post","status-publish","format-standard","hentry","category-sped","category-sped-contribuicoes","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1666"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1666\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}