{"id":1675,"date":"2025-12-09T22:36:05","date_gmt":"2025-12-10T01:36:05","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/09\/comissao-aprova-novo-criterio-de-divisao-do-icms-para-atividades-agropecuarias\/"},"modified":"2025-12-09T22:36:05","modified_gmt":"2025-12-10T01:36:05","slug":"comissao-aprova-novo-criterio-de-divisao-do-icms-para-atividades-agropecuarias","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/09\/comissao-aprova-novo-criterio-de-divisao-do-icms-para-atividades-agropecuarias\/","title":{"rendered":"Comiss\u00e3o aprova novo crit\u00e9rio de divis\u00e3o do ICMS para atividades agropecu\u00e1rias"},"content":{"rendered":"<div>\n<p>A Comiss\u00e3o de Finan\u00e7as e Tributa\u00e7\u00e3o da C\u00e2mara dos Deputados aprovou o Projeto de Lei Complementar 267\/19, que altera as regras de reparti\u00e7\u00e3o do ICMS entre os munic\u00edpios nos casos em que atividades como suinocultura, avicultura, aquicultura, silvicultura e pecu\u00e1ria de corte se estendem por mais de uma cidade. De autoria do deputado Sergio Souza [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/12\/09\/comissao-aprova-novo-criterio-de-divisao-do-icms-para-atividades-agropecuarias\/\">Comiss\u00e3o aprova novo crit\u00e9rio de divis\u00e3o do ICMS para atividades agropecu\u00e1rias<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o de Finan\u00e7as e Tributa\u00e7\u00e3o da C\u00e2mara dos Deputados aprovou o Projeto de Lei Complementar 267\/19, que altera as regras de reparti\u00e7\u00e3o do ICMS entre os munic\u00edpios nos casos em que atividades como suinocultura, avicultura, aquicultura, silvicultura e pecu\u00e1ria de corte se estendem por mais de uma cidade. De autoria do deputado Sergio Souza [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1675","post","type-post","status-publish","format-standard","hentry","category-icms","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1675"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1675\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}