{"id":1695,"date":"2025-12-15T20:41:18","date_gmt":"2025-12-15T23:41:18","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/15\/receita-federal-orienta-contribuintes-sobre-a-entrega-do-pgdas-d-e-da-defis-antes-da-entrada-em-vigor-das-novas-regras-de-multa-por-atraso\/"},"modified":"2025-12-15T20:41:18","modified_gmt":"2025-12-15T23:41:18","slug":"receita-federal-orienta-contribuintes-sobre-a-entrega-do-pgdas-d-e-da-defis-antes-da-entrada-em-vigor-das-novas-regras-de-multa-por-atraso","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/15\/receita-federal-orienta-contribuintes-sobre-a-entrega-do-pgdas-d-e-da-defis-antes-da-entrada-em-vigor-das-novas-regras-de-multa-por-atraso\/","title":{"rendered":"Receita Federal orienta contribuintes sobre a entrega do PGDAS-D e da Defis antes da entrada em vigor das novas regras de multa por atraso"},"content":{"rendered":"<div>\n<p>A Receita Federal alerta os contribuintes do Simples Nacional sobre a import\u00e2ncia da entrega tempestiva do PGDAS-D e da DEFIS, especialmente diante das novas regras de multas por atraso que passam a vigorar em 1\u00ba de janeiro de 2026. As mudan\u00e7as refor\u00e7am a estrat\u00e9gia da Institui\u00e7\u00e3o de estimular a conformidade tribut\u00e1ria, prevenir infra\u00e7\u00f5es e oferecer [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/12\/15\/receita-federal-orienta-contribuintes-sobre-entrega-pgdasd-e-defis-antes-das-novas-regras\/\">Receita Federal orienta contribuintes sobre a entrega do PGDAS-D e da Defis antes da entrada em vigor das novas regras de multa por atraso<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Receita Federal alerta os contribuintes do Simples Nacional sobre a import\u00e2ncia da entrega tempestiva do PGDAS-D e da DEFIS, especialmente diante das novas regras de multas por atraso que passam a vigorar em 1\u00ba de janeiro de 2026. As mudan\u00e7as refor\u00e7am a estrat\u00e9gia da Institui\u00e7\u00e3o de estimular a conformidade tribut\u00e1ria, prevenir infra\u00e7\u00f5es e oferecer [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274,7],"tags":[],"class_list":["post-1695","post","type-post","status-publish","format-standard","hentry","category-defis","category-rfb","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1695"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1695\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}