{"id":1710,"date":"2025-12-18T23:18:19","date_gmt":"2025-12-19T02:18:19","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/18\/receita-federal-orienta-sobre-os-procedimentos-para-o-recolhimento-do-imposto-de-renda-retido-na-fonte-sobre-lucros-e-dividendos\/"},"modified":"2025-12-18T23:18:19","modified_gmt":"2025-12-19T02:18:19","slug":"receita-federal-orienta-sobre-os-procedimentos-para-o-recolhimento-do-imposto-de-renda-retido-na-fonte-sobre-lucros-e-dividendos","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/18\/receita-federal-orienta-sobre-os-procedimentos-para-o-recolhimento-do-imposto-de-renda-retido-na-fonte-sobre-lucros-e-dividendos\/","title":{"rendered":"Receita Federal orienta sobre os procedimentos para o recolhimento do imposto de renda retido na fonte sobre lucros e dividendos"},"content":{"rendered":"<div>\n<p>Tributa\u00e7\u00e3o sobre Lucros e Dividendos a Partir de 2026 A Lei n\u00ba 15.270, de 26 de novembro de 2025, trouxe mudan\u00e7as significativas na tributa\u00e7\u00e3o da renda, incluindo a reten\u00e7\u00e3o do Imposto de Renda na Fonte (IRRF) sobre lucros e dividendos distribu\u00eddos por pessoas jur\u00eddicas a pessoas f\u00edsicas. A nova regra alcan\u00e7a rendimentos pagos tanto a [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/12\/18\/receita-federal-orienta-sobre-os-procedimentos-para-o-recolhimento-do-imposto-de-renda-retido-na-fonte-sobre-lucros-e-dividendos\/\">Receita Federal orienta sobre os procedimentos para o recolhimento do imposto de renda retido na fonte sobre lucros e dividendos<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tributa\u00e7\u00e3o sobre Lucros e Dividendos a Partir de 2026 A Lei n\u00ba 15.270, de 26 de novembro de 2025, trouxe mudan\u00e7as significativas na tributa\u00e7\u00e3o da renda, incluindo a reten\u00e7\u00e3o do Imposto de Renda na Fonte (IRRF) sobre lucros e dividendos distribu\u00eddos por pessoas jur\u00eddicas a pessoas f\u00edsicas. A nova regra alcan\u00e7a rendimentos pagos tanto a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-1710","post","type-post","status-publish","format-standard","hentry","category-rfb","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1710"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1710\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}