{"id":1723,"date":"2025-12-22T21:32:10","date_gmt":"2025-12-23T00:32:10","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/22\/oab-aciona-stf-para-contestar-impacto-da-reforma-tributaria-no-simples-nacional\/"},"modified":"2025-12-22T21:32:10","modified_gmt":"2025-12-23T00:32:10","slug":"oab-aciona-stf-para-contestar-impacto-da-reforma-tributaria-no-simples-nacional","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/22\/oab-aciona-stf-para-contestar-impacto-da-reforma-tributaria-no-simples-nacional\/","title":{"rendered":"OAB aciona STF para contestar impacto da reforma tribut\u00e1ria no Simples Nacional"},"content":{"rendered":"<div>\n<p>O Conselho Federal da Ordem dos Advogados do Brasil protocolou, no Supremo Tribunal Federal, uma a\u00e7\u00e3o direta de inconstitucionalidade para contestar dispositivos da reforma tribut\u00e1ria relacionados a empresas optantes do Simples Nacional. O objetivo, segundo o \u00f3rg\u00e3o, \u00e9 resguardar a isen\u00e7\u00e3o de Imposto de Renda sobre lucros e dividendos distribu\u00eddos por essas empresas, incluindo pequenos [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/12\/22\/oab-aciona-stf-para-contestar-impacto-da-reforma-tributaria-no-simples-nacional\/\">OAB aciona STF para contestar impacto da reforma tribut\u00e1ria no Simples Nacional<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Federal da Ordem dos Advogados do Brasil protocolou, no Supremo Tribunal Federal, uma a\u00e7\u00e3o direta de inconstitucionalidade para contestar dispositivos da reforma tribut\u00e1ria relacionados a empresas optantes do Simples Nacional. O objetivo, segundo o \u00f3rg\u00e3o, \u00e9 resguardar a isen\u00e7\u00e3o de Imposto de Renda sobre lucros e dividendos distribu\u00eddos por essas empresas, incluindo pequenos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-1723","post","type-post","status-publish","format-standard","hentry","category-reforma-tributaria","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1723"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1723\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}