{"id":1726,"date":"2025-12-23T21:40:11","date_gmt":"2025-12-24T00:40:11","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/23\/juros-sobre-capital-proprio-extemporaneos-podem-ser-deduzidos-da-base-de-calculo-do-irpj-e-da-csll\/"},"modified":"2025-12-23T21:40:11","modified_gmt":"2025-12-24T00:40:11","slug":"juros-sobre-capital-proprio-extemporaneos-podem-ser-deduzidos-da-base-de-calculo-do-irpj-e-da-csll","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/23\/juros-sobre-capital-proprio-extemporaneos-podem-ser-deduzidos-da-base-de-calculo-do-irpj-e-da-csll\/","title":{"rendered":"Juros sobre capital pr\u00f3prio extempor\u00e2neos podem ser deduzidos da base de c\u00e1lculo do IRPJ e da CSLL"},"content":{"rendered":"<div>\n<p>A Primeira Se\u00e7\u00e3o do Superior Tribunal de Justi\u00e7a (STJ) definiu, sob o rito dos recursos repetitivos, que \u00e9 poss\u00edvel a dedu\u00e7\u00e3o dos juros sobre capital pr\u00f3prio (JCP) da base de c\u00e1lculo do Imposto de Renda da Pessoa Jur\u00eddica (IRPJ) e da Contribui\u00e7\u00e3o Social sobre o Lucro L\u00edquido (CSLL), quando apurados em exerc\u00edcio anterior ao da [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/12\/23\/juros-sobre-capital-proprio-extemporaneos-podem-ser-deduzidos-da-base-de-calculo-do-irpj-e-da-csll\/\">Juros sobre capital pr\u00f3prio extempor\u00e2neos podem ser deduzidos da base de c\u00e1lculo do IRPJ e da CSLL<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Primeira Se\u00e7\u00e3o do Superior Tribunal de Justi\u00e7a (STJ) definiu, sob o rito dos recursos repetitivos, que \u00e9 poss\u00edvel a dedu\u00e7\u00e3o dos juros sobre capital pr\u00f3prio (JCP) da base de c\u00e1lculo do Imposto de Renda da Pessoa Jur\u00eddica (IRPJ) e da Contribui\u00e7\u00e3o Social sobre o Lucro L\u00edquido (CSLL), quando apurados em exerc\u00edcio anterior ao da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1726","post","type-post","status-publish","format-standard","hentry","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1726"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1726\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}