{"id":1733,"date":"2025-12-28T21:47:31","date_gmt":"2025-12-29T00:47:31","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/28\/juiza-reconhece-regularidade-cadastral-e-suspende-aumento-de-icms-st\/"},"modified":"2025-12-28T21:47:31","modified_gmt":"2025-12-29T00:47:31","slug":"juiza-reconhece-regularidade-cadastral-e-suspende-aumento-de-icms-st","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/28\/juiza-reconhece-regularidade-cadastral-e-suspende-aumento-de-icms-st\/","title":{"rendered":"Ju\u00edza reconhece regularidade cadastral e suspende aumento de ICMS-ST"},"content":{"rendered":"<div>\n<p>Por constatar que a irregularidade cadastral constatada pelo Fisco j\u00e1 havia sido afastada pela Justi\u00e7a, a 5\u00aa Vara da Fazenda P\u00fablica de S\u00e3o Lu\u00eds suspendeu, em liminar, documentos emitidos pelo governo do Maranh\u00e3o que exigiam de uma empresa o pagamento antecipado de ICMS com substitui\u00e7\u00e3o tribut\u00e1ria em um valor maior. A decis\u00e3o tamb\u00e9m pro\u00edbe o [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/12\/28\/juiza-reconhece-regularidade-cadastral-e-suspende-aumento-icms-st\/\">Ju\u00edza reconhece regularidade cadastral e suspende aumento de ICMS-ST<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por constatar que a irregularidade cadastral constatada pelo Fisco j\u00e1 havia sido afastada pela Justi\u00e7a, a 5\u00aa Vara da Fazenda P\u00fablica de S\u00e3o Lu\u00eds suspendeu, em liminar, documentos emitidos pelo governo do Maranh\u00e3o que exigiam de uma empresa o pagamento antecipado de ICMS com substitui\u00e7\u00e3o tribut\u00e1ria em um valor maior. A decis\u00e3o tamb\u00e9m pro\u00edbe o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[99,5],"tags":[],"class_list":["post-1733","post","type-post","status-publish","format-standard","hentry","category-icms-st","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1733"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1733\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}