{"id":1738,"date":"2025-12-29T20:47:38","date_gmt":"2025-12-29T23:47:38","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/29\/comissao-aprova-projeto-que-isenta-de-ipi-o-material-usado-para-adaptar-veiculo-de-pessoa-com-deficiencia\/"},"modified":"2025-12-29T20:47:38","modified_gmt":"2025-12-29T23:47:38","slug":"comissao-aprova-projeto-que-isenta-de-ipi-o-material-usado-para-adaptar-veiculo-de-pessoa-com-deficiencia","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/12\/29\/comissao-aprova-projeto-que-isenta-de-ipi-o-material-usado-para-adaptar-veiculo-de-pessoa-com-deficiencia\/","title":{"rendered":"Comiss\u00e3o aprova projeto que isenta de IPI o material usado para adaptar ve\u00edculo de pessoa com defici\u00eancia"},"content":{"rendered":"<div>\n<p>A Comiss\u00e3o de Defesa dos Direitos das Pessoas com Defici\u00eancia da C\u00e2mara dos Deputados aprovou o Projeto de Lei 5000\/25, que prev\u00ea isen\u00e7\u00e3o de Imposto sobre Produtos Industrializados (IPI) para pe\u00e7as e equipamentos necess\u00e1rios para adaptar ve\u00edculo destinado a pessoa com defici\u00eancia. O relator, deputado Duarte Jr. (PSB-MA), recomendou a aprova\u00e7\u00e3o do texto. \u201cO Estado [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/12\/29\/comissao-aprova-projeto-que-isenta-de-ipi-o-material-usado-para-adaptar-veiculo-de-pessoa-com-deficiencia\/\">Comiss\u00e3o aprova projeto que isenta de IPI o material usado para adaptar ve\u00edculo de pessoa com defici\u00eancia<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o de Defesa dos Direitos das Pessoas com Defici\u00eancia da C\u00e2mara dos Deputados aprovou o Projeto de Lei 5000\/25, que prev\u00ea isen\u00e7\u00e3o de Imposto sobre Produtos Industrializados (IPI) para pe\u00e7as e equipamentos necess\u00e1rios para adaptar ve\u00edculo destinado a pessoa com defici\u00eancia. O relator, deputado Duarte Jr. (PSB-MA), recomendou a aprova\u00e7\u00e3o do texto. \u201cO Estado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-1738","post","type-post","status-publish","format-standard","hentry","category-ipi","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1738"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1738\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}