{"id":1751,"date":"2026-01-05T20:27:44","date_gmt":"2026-01-05T23:27:44","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/05\/rs-fase-de-testes-do-sistema-de-apuracao-do-ibs-comeca-na-segunda-feira\/"},"modified":"2026-01-05T20:27:44","modified_gmt":"2026-01-05T23:27:44","slug":"rs-fase-de-testes-do-sistema-de-apuracao-do-ibs-comeca-na-segunda-feira","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/05\/rs-fase-de-testes-do-sistema-de-apuracao-do-ibs-comeca-na-segunda-feira\/","title":{"rendered":"RS: Fase de testes do sistema de apura\u00e7\u00e3o do IBS come\u00e7a na segunda-feira"},"content":{"rendered":"<div>\n<p>O Projeto Piloto do Sistema de Apura\u00e7\u00e3o Assistida do Imposto sobre Bens e Servi\u00e7os (IBS), coordenado pelo Comit\u00ea Gestor do IBS (CGIBS), come\u00e7a nesta segunda-feira (5). A iniciativa, que representa mais um passo na implementa\u00e7\u00e3o gradual da Reforma Tribut\u00e1ria do Consumo (RTC), foi regulamentada pela Portaria n\u00ba 85\/2025. O objetivo \u00e9 testar, em \u00e2mbito nacional, [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/01\/05\/rs-fase-de-testes-do-sistema-de-apuracao-do-ibs-comeca-na-segunda-feira\/\">RS: Fase de testes do sistema de apura\u00e7\u00e3o do IBS come\u00e7a na segunda-feira<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Projeto Piloto do Sistema de Apura\u00e7\u00e3o Assistida do Imposto sobre Bens e Servi\u00e7os (IBS), coordenado pelo Comit\u00ea Gestor do IBS (CGIBS), come\u00e7a nesta segunda-feira (5). A iniciativa, que representa mais um passo na implementa\u00e7\u00e3o gradual da Reforma Tribut\u00e1ria do Consumo (RTC), foi regulamentada pela Portaria n\u00ba 85\/2025. O objetivo \u00e9 testar, em \u00e2mbito nacional, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,29,5],"tags":[],"class_list":["post-1751","post","type-post","status-publish","format-standard","hentry","category-reforma-tributaria","category-sefaz","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1751"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1751\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}