{"id":1752,"date":"2026-01-05T20:36:42","date_gmt":"2026-01-05T23:36:42","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/05\/governo-da-paraiba-aumenta-isencao-de-icms-sobre-diesel-em-ate-100-e-reduz-impacto-na-passagem-de-transporte-rodoviario-coletivo\/"},"modified":"2026-01-05T20:36:42","modified_gmt":"2026-01-05T23:36:42","slug":"governo-da-paraiba-aumenta-isencao-de-icms-sobre-diesel-em-ate-100-e-reduz-impacto-na-passagem-de-transporte-rodoviario-coletivo","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/05\/governo-da-paraiba-aumenta-isencao-de-icms-sobre-diesel-em-ate-100-e-reduz-impacto-na-passagem-de-transporte-rodoviario-coletivo\/","title":{"rendered":"Governo da Para\u00edba aumenta isen\u00e7\u00e3o de ICMS sobre diesel em at\u00e9 100% e reduz impacto na passagem de transporte rodovi\u00e1rio coletivo"},"content":{"rendered":"<div>\n<p>Para reduzir o impacto do reajuste da tarifa no bolso do paraibano que usa transporte rodovi\u00e1rio coletivo, o Governo da Para\u00edba fechou acordo com os representantes das empresas do setor e elevar\u00e1 a isen\u00e7\u00e3o do ICMS sobre o \u00f3leo diesel em 100%, tanto do Sistema de Transporte Rodovi\u00e1rio Urbano da Capital paraibana, bem como das [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/01\/05\/governo-da-paraiba-aumenta-isencao-de-icms-sobre-diesel-em-ate-100-e-reduz-impacto-na-passagem-de-transporte-rodoviario-coletivo\/\">Governo da Para\u00edba aumenta isen\u00e7\u00e3o de ICMS sobre diesel em at\u00e9 100% e reduz impacto na passagem de transporte rodovi\u00e1rio coletivo<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Para reduzir o impacto do reajuste da tarifa no bolso do paraibano que usa transporte rodovi\u00e1rio coletivo, o Governo da Para\u00edba fechou acordo com os representantes das empresas do setor e elevar\u00e1 a isen\u00e7\u00e3o do ICMS sobre o \u00f3leo diesel em 100%, tanto do Sistema de Transporte Rodovi\u00e1rio Urbano da Capital paraibana, bem como das [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,281,29],"tags":[],"class_list":["post-1752","post","type-post","status-publish","format-standard","hentry","category-icms","category-pb","category-sefaz","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1752"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1752\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}