{"id":1757,"date":"2026-01-06T23:41:59","date_gmt":"2026-01-07T02:41:59","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/06\/publicacao-da-versao-11-3-7-do-programa-da-ecf\/"},"modified":"2026-01-06T23:41:59","modified_gmt":"2026-01-07T02:41:59","slug":"publicacao-da-versao-11-3-7-do-programa-da-ecf","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/06\/publicacao-da-versao-11-3-7-do-programa-da-ecf\/","title":{"rendered":"Publica\u00e7\u00e3o da Vers\u00e3o 11.3.7 do programa da ECF"},"content":{"rendered":"<div>\n<p>Foi publicada a vers\u00e3o 11.3.7 do programa da ECF, que deve ser utilizado para transmiss\u00f5es de arquivos da ECF referentes ao ano-calend\u00e1rio 2024 e situa\u00e7\u00f5es especiais de 2025 (leiaute 11), com as seguintes atualiza\u00e7\u00f5es: 1 \u2013 Corre\u00e7\u00e3o de erro envolvendo obrigatoriedade do registro X371; 2 \u2013 Melhorias de desempenho. IMPORTANTE: para aqueles contribuintes que ainda [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/01\/06\/publicacao-da-versao-11-3-7-do-programa-da-ecf\/\">Publica\u00e7\u00e3o da Vers\u00e3o 11.3.7 do programa da ECF<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foi publicada a vers\u00e3o 11.3.7 do programa da ECF, que deve ser utilizado para transmiss\u00f5es de arquivos da ECF referentes ao ano-calend\u00e1rio 2024 e situa\u00e7\u00f5es especiais de 2025 (leiaute 11), com as seguintes atualiza\u00e7\u00f5es: 1 \u2013 Corre\u00e7\u00e3o de erro envolvendo obrigatoriedade do registro X371; 2 \u2013 Melhorias de desempenho. IMPORTANTE: para aqueles contribuintes que ainda [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1757","post","type-post","status-publish","format-standard","hentry","category-sped","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1757"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1757\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}