{"id":1758,"date":"2026-01-07T19:05:57","date_gmt":"2026-01-07T22:05:57","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/07\/receita-reforca-beneficios-fiscais-que-ficam-fora-do-corte-linear-de-10\/"},"modified":"2026-01-07T19:05:57","modified_gmt":"2026-01-07T22:05:57","slug":"receita-reforca-beneficios-fiscais-que-ficam-fora-do-corte-linear-de-10","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/07\/receita-reforca-beneficios-fiscais-que-ficam-fora-do-corte-linear-de-10\/","title":{"rendered":"Receita refor\u00e7a benef\u00edcios fiscais que ficam fora do corte linear de 10%"},"content":{"rendered":"<div>\n<p>A Receita Federal publicou, na \u00faltima quarta-feira (31), a Instru\u00e7\u00e3o Normativa n\u00ba 2.305 de 2025, que detalha as regras previstas na Lei Complementar 224 de 2025, respons\u00e1vel por instituir uma redu\u00e7\u00e3o linear de 10% nos benef\u00edcios fiscais. Um dos principais pontos do documento \u00e9 a apresenta\u00e7\u00e3o, de forma nominal, dos benef\u00edcios que n\u00e3o ser\u00e3o alcan\u00e7ados [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/01\/07\/receita-reforca-beneficios-fiscais-que-ficam-fora-corte-linear\/\">Receita refor\u00e7a benef\u00edcios fiscais que ficam fora do corte linear de 10%<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Receita Federal publicou, na \u00faltima quarta-feira (31), a Instru\u00e7\u00e3o Normativa n\u00ba 2.305 de 2025, que detalha as regras previstas na Lei Complementar 224 de 2025, respons\u00e1vel por instituir uma redu\u00e7\u00e3o linear de 10% nos benef\u00edcios fiscais. Um dos principais pontos do documento \u00e9 a apresenta\u00e7\u00e3o, de forma nominal, dos benef\u00edcios que n\u00e3o ser\u00e3o alcan\u00e7ados [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1758","post","type-post","status-publish","format-standard","hentry","category-rfb","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1758"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1758\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}