{"id":1768,"date":"2026-01-12T00:04:21","date_gmt":"2026-01-12T03:04:21","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/12\/programa-de-conformidade-da-receita-tem-atendimento-previo-a-bons-contribuintes\/"},"modified":"2026-01-12T00:04:21","modified_gmt":"2026-01-12T03:04:21","slug":"programa-de-conformidade-da-receita-tem-atendimento-previo-a-bons-contribuintes","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/12\/programa-de-conformidade-da-receita-tem-atendimento-previo-a-bons-contribuintes\/","title":{"rendered":"Programa de conformidade da Receita tem atendimento pr\u00e9vio a bons contribuintes"},"content":{"rendered":"<div>\n<p>A Receita Federal instituiu, no final de dezembro, um programa de conformidade voltado ao atendimento pr\u00e9vio de bons contribuintes. A iniciativa, publicada na Portaria RFB 627, prev\u00ea um monitoramento fiscal cont\u00ednuo das empresas. Segundo especialistas, ser\u00e1 aberto um canal de di\u00e1logo ativo entre fisco e contribuinte antes de medidas fiscalizat\u00f3rias. Diferentemente dos programas de transa\u00e7\u00e3o [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/01\/09\/programa-de-conformidade-da-receita-tem-atendimento-previo-a-bons-contribuintes\/\">Programa de conformidade da Receita tem atendimento pr\u00e9vio a bons contribuintes<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Receita Federal instituiu, no final de dezembro, um programa de conformidade voltado ao atendimento pr\u00e9vio de bons contribuintes. A iniciativa, publicada na Portaria RFB 627, prev\u00ea um monitoramento fiscal cont\u00ednuo das empresas. Segundo especialistas, ser\u00e1 aberto um canal de di\u00e1logo ativo entre fisco e contribuinte antes de medidas fiscalizat\u00f3rias. Diferentemente dos programas de transa\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1768","post","type-post","status-publish","format-standard","hentry","category-rfb","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1768"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1768\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}