{"id":1774,"date":"2026-01-12T21:54:17","date_gmt":"2026-01-13T00:54:17","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/12\/declaraagro-arrendamentos-contribuintes-ja-regularizaram-mais-de-400-declaracoes-junto-a-receita-federal\/"},"modified":"2026-01-12T21:54:17","modified_gmt":"2026-01-13T00:54:17","slug":"declaraagro-arrendamentos-contribuintes-ja-regularizaram-mais-de-400-declaracoes-junto-a-receita-federal","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/12\/declaraagro-arrendamentos-contribuintes-ja-regularizaram-mais-de-400-declaracoes-junto-a-receita-federal\/","title":{"rendered":"DeclaraAgro \u2013 Arrendamentos: Contribuintes j\u00e1 regularizaram mais de 400 declara\u00e7\u00f5es junto \u00e0 Receita Federal"},"content":{"rendered":"<div>\n<p>Faltando poucas semanas para o encerramento do prazo, que termina em 30 de janeiro, a opera\u00e7\u00e3o DeclaraAgro \u2013 Arrendamentos j\u00e1 resultou na regulariza\u00e7\u00e3o de mais de 400 declara\u00e7\u00f5es junto \u00e0 Receita Federal, totalizando aproximadamente R$ 135 milh\u00f5es corretamente declarados. Um m\u00eas ap\u00f3s iniciar a A\u00e7\u00e3o de Conformidade Declara Agro \u2013 Arrendamentos, a ades\u00e3o \u00e0 autorregulariza\u00e7\u00e3o [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/01\/12\/declaraagro-arrendamentos-contribuintes-ja-regularizaram-mais-de-400-declaracoes-junto-a-receita-federal\/\">DeclaraAgro \u2013 Arrendamentos: Contribuintes j\u00e1 regularizaram mais de 400 declara\u00e7\u00f5es junto \u00e0 Receita Federal<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Faltando poucas semanas para o encerramento do prazo, que termina em 30 de janeiro, a opera\u00e7\u00e3o DeclaraAgro \u2013 Arrendamentos j\u00e1 resultou na regulariza\u00e7\u00e3o de mais de 400 declara\u00e7\u00f5es junto \u00e0 Receita Federal, totalizando aproximadamente R$ 135 milh\u00f5es corretamente declarados. Um m\u00eas ap\u00f3s iniciar a A\u00e7\u00e3o de Conformidade Declara Agro \u2013 Arrendamentos, a ades\u00e3o \u00e0 autorregulariza\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[286,7],"tags":[],"class_list":["post-1774","post","type-post","status-publish","format-standard","hentry","category-declaraagro","category-rfb","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1774"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1774\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}