{"id":1777,"date":"2026-01-12T22:21:17","date_gmt":"2026-01-13T01:21:17","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/12\/publicada-atualizacao-do-manual-da-ecd\/"},"modified":"2026-01-12T22:21:17","modified_gmt":"2026-01-13T01:21:17","slug":"publicada-atualizacao-do-manual-da-ecd","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/12\/publicada-atualizacao-do-manual-da-ecd\/","title":{"rendered":"Publicada atualiza\u00e7\u00e3o do Manual da ECD"},"content":{"rendered":"<div>\n<p>J\u00e1 est\u00e1 dispon\u00edvel no endere\u00e7o https:\/\/sped.rfb.gov.br\/pasta\/show\/1569 o Manual da ECD atualizado. J\u00e1 o Programa Gerador de Escritura\u00e7\u00e3o (PGE) da ECD na vers\u00e3o 10.3.4 deve ser publicado a partir do dia 19\/01\/2026 . A grande novidade \u00e9 a possibilidade, a partir da emiss\u00e3o de CNPJ alfanum\u00e9rico, de entregas de ECD com o novo formato do CNPJ. [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/01\/12\/publicada-atualizacao-do-manual-da-ecd\/\">Publicada atualiza\u00e7\u00e3o do Manual da ECD<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 est\u00e1 dispon\u00edvel no endere\u00e7o https:\/\/sped.rfb.gov.br\/pasta\/show\/1569 o Manual da ECD atualizado. J\u00e1 o Programa Gerador de Escritura\u00e7\u00e3o (PGE) da ECD na vers\u00e3o 10.3.4 deve ser publicado a partir do dia 19\/01\/2026 . A grande novidade \u00e9 a possibilidade, a partir da emiss\u00e3o de CNPJ alfanum\u00e9rico, de entregas de ECD com o novo formato do CNPJ. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,14],"tags":[],"class_list":["post-1777","post","type-post","status-publish","format-standard","hentry","category-ecd","category-sped","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1777"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1777\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}