{"id":1803,"date":"2026-01-20T22:08:04","date_gmt":"2026-01-21T01:08:04","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/20\/publicacao-da-versao-10-3-5-do-programa-da-ecd\/"},"modified":"2026-01-20T22:08:04","modified_gmt":"2026-01-21T01:08:04","slug":"publicacao-da-versao-10-3-5-do-programa-da-ecd","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/20\/publicacao-da-versao-10-3-5-do-programa-da-ecd\/","title":{"rendered":"Publica\u00e7\u00e3o da vers\u00e3o 10.3.5 do programa da ECD"},"content":{"rendered":"<div>\n<p>Publicada a vers\u00e3o 10.3.5 do programa da ECD, v\u00e1lida para o ano-calend\u00e1rio 2025, situa\u00e7\u00f5es especiais 2026 e anos anteriores, no endere\u00e7o ECD \u2014 Receita Federal. Foram inclu\u00eddas as seguintes atualiza\u00e7\u00f5es: Corre\u00e7\u00e3o de erro ao tentar validar a escritura\u00e7\u00e3o. Importante ressaltar que n\u00e3o houve altera\u00e7\u00f5es de regras de neg\u00f3cios. Para a transmiss\u00e3o da ECD, \u00e9 preciso [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/01\/20\/publicacao-da-versao-10-3-5-do-programa-da-ecd\/\">Publica\u00e7\u00e3o da vers\u00e3o 10.3.5 do programa da ECD<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Publicada a vers\u00e3o 10.3.5 do programa da ECD, v\u00e1lida para o ano-calend\u00e1rio 2025, situa\u00e7\u00f5es especiais 2026 e anos anteriores, no endere\u00e7o ECD \u2014 Receita Federal. Foram inclu\u00eddas as seguintes atualiza\u00e7\u00f5es: Corre\u00e7\u00e3o de erro ao tentar validar a escritura\u00e7\u00e3o. Importante ressaltar que n\u00e3o houve altera\u00e7\u00f5es de regras de neg\u00f3cios. Para a transmiss\u00e3o da ECD, \u00e9 preciso [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1803","post","type-post","status-publish","format-standard","hentry","category-sped","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1803"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1803\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}