{"id":1812,"date":"2026-01-22T21:29:59","date_gmt":"2026-01-23T00:29:59","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/22\/60-das-teses-tributarias-de-repercussao-geral-do-stf-desde-2007-sao-pro-fisco\/"},"modified":"2026-01-22T21:29:59","modified_gmt":"2026-01-23T00:29:59","slug":"60-das-teses-tributarias-de-repercussao-geral-do-stf-desde-2007-sao-pro-fisco","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/22\/60-das-teses-tributarias-de-repercussao-geral-do-stf-desde-2007-sao-pro-fisco\/","title":{"rendered":"60% das teses tribut\u00e1rias de repercuss\u00e3o geral do STF desde 2007 s\u00e3o pr\u00f3-Fisco"},"content":{"rendered":"<div>\n<p>Nos casos tribut\u00e1rios de repercuss\u00e3o geral julgados pelo Supremo Tribunal Federal desde o in\u00edcio dessa sistem\u00e1tica (em 2007), 60,6% das decis\u00f5es foram favor\u00e1veis ao Fisco. Por outro lado, apenas 37,7% dessas a\u00e7\u00f5es tiveram desfecho pr\u00f3-contribuinte. As informa\u00e7\u00f5es foram publicadas pelo Valor Econ\u00f4mico. Quando considerados apenas os casos relativos a PIS e Cofins, 62% das decis\u00f5es [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/01\/22\/60-das-teses-tributarias-de-repercussao-geral-do-stf-desde-2007-sao-pro-fisco\/\">60% das teses tribut\u00e1rias de repercuss\u00e3o geral do STF desde 2007 s\u00e3o pr\u00f3-Fisco<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nos casos tribut\u00e1rios de repercuss\u00e3o geral julgados pelo Supremo Tribunal Federal desde o in\u00edcio dessa sistem\u00e1tica (em 2007), 60,6% das decis\u00f5es foram favor\u00e1veis ao Fisco. Por outro lado, apenas 37,7% dessas a\u00e7\u00f5es tiveram desfecho pr\u00f3-contribuinte. As informa\u00e7\u00f5es foram publicadas pelo Valor Econ\u00f4mico. Quando considerados apenas os casos relativos a PIS e Cofins, 62% das decis\u00f5es [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-1812","post","type-post","status-publish","format-standard","hentry","category-fisco","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1812"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1812\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}