{"id":1817,"date":"2026-01-26T21:09:18","date_gmt":"2026-01-27T00:09:18","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/26\/fisco-estadual-nao-pode-usar-dados-do-contribuinte-sem-norma-propria\/"},"modified":"2026-01-26T21:09:18","modified_gmt":"2026-01-27T00:09:18","slug":"fisco-estadual-nao-pode-usar-dados-do-contribuinte-sem-norma-propria","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/01\/26\/fisco-estadual-nao-pode-usar-dados-do-contribuinte-sem-norma-propria\/","title":{"rendered":"Fisco estadual n\u00e3o pode usar dados do contribuinte sem norma pr\u00f3pria"},"content":{"rendered":"<div>\n<p>Conforme decidido pelo Supremo Tribunal Federal na ADI 2.390, a validade do acesso de Fiscos estaduais a dados banc\u00e1rios de contribuintes depende da exist\u00eancia de regulamenta\u00e7\u00e3o local que espelhe as garantias do Decreto Federal 3.724\/2001. A falta de norma espec\u00edfica assegurando o sigilo e o devido processo legal torna nulo o lan\u00e7amento tribut\u00e1rio baseado nessas [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/01\/26\/fisco-estadual-nao-pode-usar-dados-do-contribuinte-sem-norma-propria\/\">Fisco estadual n\u00e3o pode usar dados do contribuinte sem norma pr\u00f3pria<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Conforme decidido pelo Supremo Tribunal Federal na ADI 2.390, a validade do acesso de Fiscos estaduais a dados banc\u00e1rios de contribuintes depende da exist\u00eancia de regulamenta\u00e7\u00e3o local que espelhe as garantias do Decreto Federal 3.724\/2001. A falta de norma espec\u00edfica assegurando o sigilo e o devido processo legal torna nulo o lan\u00e7amento tribut\u00e1rio baseado nessas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-1817","post","type-post","status-publish","format-standard","hentry","category-fisco","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1817"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1817\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}