{"id":1914,"date":"2026-02-24T22:30:19","date_gmt":"2026-02-25T01:30:19","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/02\/24\/split-payment-e-o-coracao-da-reforma-tributaria-do-consumo-afirma-presidente-da-confederacao-nacional-das-instituicoes-financeiras\/"},"modified":"2026-02-24T22:30:19","modified_gmt":"2026-02-25T01:30:19","slug":"split-payment-e-o-coracao-da-reforma-tributaria-do-consumo-afirma-presidente-da-confederacao-nacional-das-instituicoes-financeiras","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/02\/24\/split-payment-e-o-coracao-da-reforma-tributaria-do-consumo-afirma-presidente-da-confederacao-nacional-das-instituicoes-financeiras\/","title":{"rendered":"Split payment \u00e9 o \u201ccora\u00e7\u00e3o\u201d da reforma tribut\u00e1ria do consumo, afirma presidente da Confedera\u00e7\u00e3o Nacional das Institui\u00e7\u00f5es Financeiras"},"content":{"rendered":"<div>\n<p>Estudos relacionados ao desenvolvimento do split payment foram iniciados ainda em 2024, antes da aprova\u00e7\u00e3o do projeto na C\u00e2mara dos Deputados, afirmou Cristiane Coelho, presidente da Confedera\u00e7\u00e3o Nacional das Institui\u00e7\u00f5es Financeiras (Fin). A declara\u00e7\u00e3o foi feita durante o workshop \u201cSplit Payment da Reforma Tribut\u00e1ria \u2013 Conceitos e Requisitos Operacionais\u201d, realizado nesta 2\u00aa feira em S\u00e3o [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/02\/24\/split-payment-e-o-coracao-da-reforma-tributaria-do-consumo-afirma-presidente-da-confederacao-nacional-das-instituicoes-financeiras\/\">Split payment \u00e9 o \u201ccora\u00e7\u00e3o\u201d da reforma tribut\u00e1ria do consumo, afirma presidente da Confedera\u00e7\u00e3o Nacional das Institui\u00e7\u00f5es Financeiras<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estudos relacionados ao desenvolvimento do split payment foram iniciados ainda em 2024, antes da aprova\u00e7\u00e3o do projeto na C\u00e2mara dos Deputados, afirmou Cristiane Coelho, presidente da Confedera\u00e7\u00e3o Nacional das Institui\u00e7\u00f5es Financeiras (Fin). A declara\u00e7\u00e3o foi feita durante o workshop \u201cSplit Payment da Reforma Tribut\u00e1ria \u2013 Conceitos e Requisitos Operacionais\u201d, realizado nesta 2\u00aa feira em S\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,221],"tags":[],"class_list":["post-1914","post","type-post","status-publish","format-standard","hentry","category-reforma-tributaria","category-reforma-tributaria-do-consumo","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1914"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1914\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}