{"id":1961,"date":"2026-03-10T21:18:41","date_gmt":"2026-03-11T00:18:41","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/03\/10\/conselho-superior-elege-presidente-e-vices-para-a-gestao-do-comite-gestor-do-ibs-ate-2027\/"},"modified":"2026-03-10T21:18:41","modified_gmt":"2026-03-11T00:18:41","slug":"conselho-superior-elege-presidente-e-vices-para-a-gestao-do-comite-gestor-do-ibs-ate-2027","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/03\/10\/conselho-superior-elege-presidente-e-vices-para-a-gestao-do-comite-gestor-do-ibs-ate-2027\/","title":{"rendered":"Conselho Superior elege presidente e vices para a gest\u00e3o do Comit\u00ea Gestor do IBS at\u00e9 2027"},"content":{"rendered":"<div>\n<p>O Conselho Superior do Comit\u00ea Gestor do Imposto sobre Bens e Servi\u00e7os (CGIBS) ratificou, por unanimidade, o secret\u00e1rio de Fazenda de Mato Grosso do Sul, Fl\u00e1vio C\u00e9sar Mendes de Oliveira, para a presid\u00eancia da entidade at\u00e9 mar\u00e7o de 2027. Na mesma reuni\u00e3o, tamb\u00e9m foram escolhidos os dois vice-presidentes: Luiz Felipe Vidal Arellano, secret\u00e1rio da Fazenda [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/03\/10\/conselho-superior-elege-presidente-e-vices-para-a-gestao-do-comite-gestor-do-ibs-ate-2027\/\">Conselho Superior elege presidente e vices para a gest\u00e3o do Comit\u00ea Gestor do IBS at\u00e9 2027<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Superior do Comit\u00ea Gestor do Imposto sobre Bens e Servi\u00e7os (CGIBS) ratificou, por unanimidade, o secret\u00e1rio de Fazenda de Mato Grosso do Sul, Fl\u00e1vio C\u00e9sar Mendes de Oliveira, para a presid\u00eancia da entidade at\u00e9 mar\u00e7o de 2027. Na mesma reuni\u00e3o, tamb\u00e9m foram escolhidos os dois vice-presidentes: Luiz Felipe Vidal Arellano, secret\u00e1rio da Fazenda [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[104,17],"tags":[],"class_list":["post-1961","post","type-post","status-publish","format-standard","hentry","category-ibs","category-reforma-tributaria","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1961"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1961\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}