{"id":1971,"date":"2026-03-12T22:22:25","date_gmt":"2026-03-13T01:22:25","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/03\/12\/stj-nega-credito-presumido-de-ipi-sobre-exportacao-de-produto-nao-tributado\/"},"modified":"2026-03-12T22:22:25","modified_gmt":"2026-03-13T01:22:25","slug":"stj-nega-credito-presumido-de-ipi-sobre-exportacao-de-produto-nao-tributado","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/03\/12\/stj-nega-credito-presumido-de-ipi-sobre-exportacao-de-produto-nao-tributado\/","title":{"rendered":"STJ nega cr\u00e9dito presumido de IPI sobre exporta\u00e7\u00e3o de produto n\u00e3o tributado"},"content":{"rendered":"<div>\n<p>A 2\u00aa Turma do Superior Tribunal de Justi\u00e7a (STJ) decidiu na ter\u00e7a-feira (10\/3), por unanimidade, que receitas de exporta\u00e7\u00e3o de produtos classificados como n\u00e3o tributados (NT) pelo IPI n\u00e3o podem integrar a base de c\u00e1lculo do cr\u00e9dito presumido do imposto. A decis\u00e3o \u00e9 favor\u00e1vel \u00e0 Fazenda, que recorria de ac\u00f3rd\u00e3o desfavor\u00e1vel na origem e defendia [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/03\/12\/stj-nega-credito-presumido-de-ipi-sobre-exportacao-de-produto-nao-tributado\/\">STJ nega cr\u00e9dito presumido de IPI sobre exporta\u00e7\u00e3o de produto n\u00e3o tributado<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A 2\u00aa Turma do Superior Tribunal de Justi\u00e7a (STJ) decidiu na ter\u00e7a-feira (10\/3), por unanimidade, que receitas de exporta\u00e7\u00e3o de produtos classificados como n\u00e3o tributados (NT) pelo IPI n\u00e3o podem integrar a base de c\u00e1lculo do cr\u00e9dito presumido do imposto. A decis\u00e3o \u00e9 favor\u00e1vel \u00e0 Fazenda, que recorria de ac\u00f3rd\u00e3o desfavor\u00e1vel na origem e defendia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1971","post","type-post","status-publish","format-standard","hentry","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1971"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1971\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}