{"id":1974,"date":"2026-03-15T22:39:29","date_gmt":"2026-03-16T01:39:29","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/03\/15\/receita-federal-atualiza-manual-de-exportacao-apos-incidencia-de-imposto-de-exportacao-sobre-petroleo-e-diesel\/"},"modified":"2026-03-15T22:39:29","modified_gmt":"2026-03-16T01:39:29","slug":"receita-federal-atualiza-manual-de-exportacao-apos-incidencia-de-imposto-de-exportacao-sobre-petroleo-e-diesel","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/03\/15\/receita-federal-atualiza-manual-de-exportacao-apos-incidencia-de-imposto-de-exportacao-sobre-petroleo-e-diesel\/","title":{"rendered":"Receita Federal atualiza Manual de Exporta\u00e7\u00e3o ap\u00f3s incid\u00eancia de Imposto de Exporta\u00e7\u00e3o sobre Petr\u00f3leo e Diesel"},"content":{"rendered":"<div>\n<p>A Receita Federal informa que a p\u00e1gina relativa ao Imposto de Exporta\u00e7\u00e3o (IE) j\u00e1 se encontra devidamente atualizada no Manual de Exporta\u00e7\u00e3o, refletindo as altera\u00e7\u00f5es trazidas pela Medida Provis\u00f3ria n\u00ba 1.340, de 12 de mar\u00e7o de 2026. Historicamente restrito a casos espec\u00edficos, como a exporta\u00e7\u00e3o de cigarros para determinadas regi\u00f5es da Am\u00e9rica, o Imposto de [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/03\/15\/receita-federal-atualiza-manual-de-exportacao-apos-incidencia-de-imposto-de-exportacao-sobre-petroleo-e-diesel\/\">Receita Federal atualiza Manual de Exporta\u00e7\u00e3o ap\u00f3s incid\u00eancia de Imposto de Exporta\u00e7\u00e3o sobre Petr\u00f3leo e Diesel<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Receita Federal informa que a p\u00e1gina relativa ao Imposto de Exporta\u00e7\u00e3o (IE) j\u00e1 se encontra devidamente atualizada no Manual de Exporta\u00e7\u00e3o, refletindo as altera\u00e7\u00f5es trazidas pela Medida Provis\u00f3ria n\u00ba 1.340, de 12 de mar\u00e7o de 2026. Historicamente restrito a casos espec\u00edficos, como a exporta\u00e7\u00e3o de cigarros para determinadas regi\u00f5es da Am\u00e9rica, o Imposto de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[303,7,5],"tags":[],"class_list":["post-1974","post","type-post","status-publish","format-standard","hentry","category-receita-federal-atualiza-manual-de-exportacao","category-rfb","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=1974"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/1974\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=1974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=1974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=1974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}